{"id":160268,"date":"2023-01-20T11:43:14","date_gmt":"2023-01-20T10:43:14","guid":{"rendered":"https:\/\/wassermann-group.com\/products\/werkzeugspeicher-tool-d\/"},"modified":"2026-05-28T13:18:39","modified_gmt":"2026-05-28T11:18:39","slug":"werkzeugspeicher-tool-d","status":"publish","type":"products","link":"https:\/\/wassermann-group.com\/it\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\/werkzeugspeicher-tool-d\/","title":{"rendered":"TOOL-D No.XXX"},"content":{"rendered":"\n<!-- BEGIN filter_Blick -->\n<div class=\"filter-block wassermann_block\">\n    <!-- BEGIN col -->\n  <div class=\"col\">\n\n    <!-- BEGIN IMAGES -->\n    <div class=\"col lg_4 md_12  sm_12\">\n          <div class=\"mobile h1 custom_headline\">\r\n        <b><p>Negozio di utensili TOOL-D<\/p>\n<\/b>\r\n    <\/div>\r\n              <section id=\"main-carousel\" class=\"splide\">\r\n          <div class=\"splide__track\">\r\n            <ul class=\"splide__list\">\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/Tool-D.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/Tool-D-420x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/cnc-automation-werkzeugspeicher-tool-l-zentralmagazin-700x854.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/cnc-automation-werkzeugspeicher-tool-l-zentralmagazin-369x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/06\/cnc-automation-werkzeugspeicher-tool-l-stand-alone-speicher-700x466.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/06\/cnc-automation-werkzeugspeicher-tool-l-stand-alone-speicher-676x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/9561-700x1050.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/9561-scaled.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/cnc-automation-patentierter-werkzeugspeicher-700x467.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/cnc-automation-patentierter-werkzeugspeicher-675x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-1-2.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-1-2-427x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-2-2.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-2-2-612x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-3-2.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-3-2-426x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/0357_1-TOOL-D-700x701.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/0357_1-TOOL-D-450x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/Tool-S.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/Tool-S-420x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                          <\/ul>\r\n          <\/div>\r\n        <\/section>\r\n\r\n        <section id=\"thumbnail-carousel\" class=\"splide\">\r\n          <div class=\"splide__track\">\r\n            <ul class=\"splide__list\">\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/Tool-D-120x128.jpg\" alt=\"\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/cnc-automation-werkzeugspeicher-tool-l-zentralmagazin-120x146.jpg\" alt=\"CNC Automation Werkzeugspeicher TOOL-L Zentralmagazin\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/06\/cnc-automation-werkzeugspeicher-tool-l-stand-alone-speicher-120x80.jpg\" alt=\"CNC Automation Werkzeugspeicher TOOL-L Stand-Alone-Speicher\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/9561-120x180.jpg\" alt=\"\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/cnc-automation-patentierter-werkzeugspeicher-120x80.jpg\" alt=\"CNC Automation patentierter Werkzeugspeicher\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-1-2-120x126.jpg\" alt=\"\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-2-2-120x88.jpg\" alt=\"\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-3-2-120x127.jpg\" alt=\"\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/0357_1-TOOL-D-120x120.jpg\" alt=\"\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/Tool-S-120x128.jpg\" alt=\"\">\r\n                <\/li>\r\n              \r\n            <\/ul>\r\n          <\/div>\r\n        <\/section>\r\n          <\/div>\n    <!-- END IMAGES -->\n\n    <!-- BEGIN DETAILS -->\n    <div class=\"col stretch lg_8 md_12  sm_12\">\n      <div class=\"product_headline_wrapper\">\r\n                  <h1 id=\"negozio-di-utensili-tool-d-il-miracolo-dello-spazio-lo-strumento-terminale-per-le-massime-prestazioni\" id=\"negozio-di-utensili-tool-d-il-miracolo-dello-spazio-lo-strumento-terminale-per-le-massime-prestazioni\">\r\n            <span class=\"headline-desc\"><p>Negozio di utensili TOOL-D<\/p>\n<\/span>\r\n          <\/h1>\r\n\r\n                                    <h2 class=\"h1 custom_headline table-wrapper\" style=\"margin-top:0\">\r\n                Il miracolo dello spazio &#8211; Lo strumento TERMINALE per le massime prestazioni<\/h2>\r\n                                    <\/div>\n      <!-- BEGIN text_content -->\n      <div class=\"table-wrapper \">\n        \r\n    <!-- full -->\r\n            \r\n    <div class=\"content\">\r\n    <p>Il nostro TOOL-TERMINAL TOOL-D \u00e8 ideale per essere collegato a tutti i tipi di centri di lavoro, fresatrici e centri di tornitura\/fresatura come magazzino aggiuntivo al magazzino della macchina esistente. Grazie alle sue dimensioni compatte e all&#8217;imbattibile densit\u00e0 di imballaggio, fino a 550 utensili, TOOL-D pu\u00f2 essere facilmente adattato a quasi tutte le macchine esistenti. La soluzione \u00e8 ideale anche come magazzino decentralizzato o magazzino di alimentazione per pi\u00f9 macchine contemporaneamente.  <\/p>\n    <\/div>\r\n\n\n                      <p class=\"h3 custom_headline\"><b>Vantaggi<\/b><\/p>\r\n          <!-- BEGIN content -->\n          <div class=\"content\">\n            <ul>\n<li class=\"ewa-rteLine\"><strong>Risparmio di spazio<\/strong> &#8211; alta densit\u00e0 di utensili, ad esempio 552 utensili su soli 3,5 m\u00b2.<\/li>\n<li class=\"ewa-rteLine\"><strong>Generalista<\/strong>&#8211; per tutti i comuni portautensili<\/li>\n<li class=\"ewa-rteLine\">Archiviazione <strong>aperta<\/strong> con interfacce per la gestione degli utensili, la preimpostazione degli utensili e la produzione.<\/li>\n<li class=\"ewa-rteLine\"><strong>Produttivo<\/strong> &#8211; riduce i tempi di inattivit\u00e0 con gli stampi gemelli<\/li>\n<li class=\"ewa-rteLine\"><strong>Personalizzato<\/strong> &#8211; tre architetture di base per configurazioni flessibili<\/li>\n<\/ul>\n            \n                          <!-- BEGIN button_wrapper (full) -->\r\n        <div class=\" btn-wrapper-prod\">\r\n\r\n          <div class=\"button-controll-wrapper\">\r\n            <a href=\"#configuration\" class=\"button blue\" title=\"Configurare \"\r\n              id=\"configure-link-accordion\">\r\n              Configurazione personalizzata            <\/a>\r\n          <\/div>\r\n\r\n          <div class=\"button-controll-wrapper\">\r\n            <a href=\"#\" class=\"button orange more_mail_prod\" title=\"e-mail\"\r\n              data-title=\"Negozio di utensili TOOL-D\">\r\n              Richiesta di prodotti            <\/a>\r\n          <\/div>\r\n\r\n\r\n          <div class=\"button-controll-wrapper\">\r\n            <a href=\"#\" class=\"button orange outline compare_select\" data-id=\"160268\"\r\n              title=\"Confronta i prodotti\"\r\n              data-enabled-text=\"Confronta i prodotti\"\r\n              data-disabled-text=\"Rimuovere dal confronto\"\r\n              data-title=\"Negozio di utensili TOOL-D\">\r\n              Confronta i prodotti            <\/a>\r\n          <\/div>\r\n\r\n        <\/div>\r\n        <!-- END button_wrapper (full) -->            \n                      <\/div>\n          <!-- END content -->\n        \n        \n    <\/div>\n    <!-- END text_content -->\n\n    \n  <\/div>\n  <!-- END DETAILS -->\n\n      \r\n  <!-- \/\/Headline -->\r\n\r\n      <div class=\"col lg_8 md_12 sm_12 no-margin right_headline\">\r\n      <p class=\"h3 custom_headline\" style=\"width:100%\"><b>Informazioni tecniche<\/b>\r\n      <\/p>\r\n    <\/div>\r\n        <!-- BEGIN Modell (full) -->\r\n    <div class=\"col lg_4 md_12 sm_12\">\r\n      <div class=\"\" style=\"width:100%\">\r\n        \r\n        \r\n          \r\n          <div class=\"button-controll-wrapper\">\r\n            \r\n                                                      <div class=\"desc\">\r\n                  <a target=\"_blank\" class=\"\"\r\n                    href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/09\/TOOL-D-Datenblatt_WT_2200905.pdf\">\r\n                    TOOL-D-Datenblatt                  <\/a>\r\n                <\/div>\r\n                                      <div class=\"button-wrapper\">\r\n              <a target=\"_blank\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/09\/TOOL-D-Datenblatt_WT_2200905.pdf\"\r\n                class=\"button outline blue \">\r\n                                  <span>Scheda tecnica<\/span>\r\n                              <\/a>\r\n            <\/div>\r\n          <\/div>\r\n              <\/div>\r\n    <\/div>\r\n    <!-- END Modell (full) -->\r\n    <!-- BEGIN table_block -->\r\n  <div class=\"col lg_8 md_12 sm_12\">\r\n    <!-- BEGIN table_wrapper -->\r\n    <div class=\"table-wrapper \">\r\n              <div class=\"table_header\">\r\n          Dati tecnici        <\/div>\r\n      \r\n<!-- BEGIN table -->\r\n<div class=\"table\">\r\n\r\n                  <div class=\"col             \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                storage architecture              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  Compact circular storage system                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col             \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                Number of tools:              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  600 pcs.                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col             \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                Tool holder              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  All common                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col hidden            \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                max. tool diameter              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  280 mm                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col hidden            \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                max. tool length              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  500 mm                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col hidden            \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                Tool weights              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  25 kg                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col hidden            \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                Footprint              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  4.2 m\u00b2                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col hidden            \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                Dimensions &#8211; depth              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  2511 mm                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col hidden            \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                Dimensions &#8211; width              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  1700 mm                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col hidden            \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                Dimensions &#8211; height              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  2967 mm                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col hidden            \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                Terminal control              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  BECKHOFF TwinCAT3                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                \r\n      <\/div>\r\n    <!-- END table -->\r\n        <a href=\"#\" class=\"more-filter\">Mostra tutti i dati<i class=\"arrow down\"><\/i><\/a>\r\n        <div class=\"button-controll-wrapper\">\r\n          <a href=\"#\" class=\"button orange more_mail_prod\" title=\"e-mail\"\r\n            data-title=\"Negozio di utensili TOOL-D\">\r\n            Richiesta di prodotti          <\/a>\r\n        <\/div>\r\n          <\/div>\r\n    <!-- END table_wrapper -->\r\n  <\/div>\r\n  <!-- END table_block -->\n          <div class=\"clearfix lg_12 md_12 sm_12\"><\/div>\n      \n      <!-- BEGIN OFFER -->\r\n    <div class=\"lg_4 md_12 sm_12\">\r\n          <\/div>\r\n    <!-- END OFFER -->\r\n  \n  <!-- BEGIN config -->\n  <div class=\"lg_8 md_12 sm_12\">\n    <!-- BEGIN Table -->\n    <div class=\"table-wrapper\" id=\"configuration\">\n              <span class=\"h2 custom_headline\" style=\"display: none;\">\r\n          <p>Non sono i parametri giusti?<br \/>\n<strong>Personalizzi ora!<\/strong><\/p>\n        <\/span>\r\n            <!-- BEGIN Filter -->\n      <div class=\"filter \">\n        \r\n<!-- BEGIN Akkordion -->\r\n        <div class=\"filter-accordion-container filter-accordion-block accordion-container accordion-block\">\r\n          <!-- Haben Sie noch Fragen zu dem Produkt? + NEW FORM -->\r\n          <div class=\"filter-accordion_entry accordion_entry\">\r\n            <a href=\"#\" class=\"headline\" role=\"button\" id=\"faq_toggler__1\" aria-controls=\"faq_content__1\" aria-expanded=\"true\" class=\"headline active\">\r\n              <p class=\"h3 headline\">\r\n                Ha qualche domanda sul prodotto?              <\/p>\r\n            <\/a>\r\n            <div class=\"filter-accordion_content accordion_content\" style=\"display: none;\">\r\n              \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f153078-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"153078\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/products\/160268#wpcf7-f153078-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Modulo di contatto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"153078\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f153078-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"col lg_6\">\n\t<p><label for=\"firstname\">Nome*<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"firstname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"firstname\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"col lg_6\">\n\t<p><label for=\"name\">Nome*<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"name\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"col lg_6\">\n\t<p><label for=\"company\">Azienda<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"company\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"col lg_6\">\n\t<p><label for=\"email\">Indirizzo e-mail*<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"col lg_12\">\n\t<p><label for=\"message\">La sua domanda<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"message\"><\/textarea><\/span>\n\t<\/p>\n<\/div>\n<div class=\"col lg_12 checkbox\">\n\t<div>\n\t\t<p>Dopo aver inviato il modulo, i miei dati saranno utilizzati per elaborare e rispondere alla mia richiesta. Ho preso nota delle <a href=\"https:\/\/wassermann-automation.com\/datenschutz\/\" target=\"_blank\">informazioni sulla protezione dei dati<\/a>.\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"col lg_12 checkbox\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"kontakt\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"kontakt[]\" value=\"S\u00ec\" \/><span class=\"wpcf7-list-item-label\">S\u00ec<\/span><\/span><\/span><\/span>\n\t<\/p>\n\t<div>\n\t\t<p><label for=\"kontakt\">Acconsento a che la WASSERMANN TECHNOLOGIE GmbH tratti regolarmente i miei dati per l\u2019invio di una newsletter via e-mail (informazioni su offerte, promozioni, prodotti e servizi della WASSERMANN TECHNOLOGIE GmbH). Il presente consenso \u00e8 volontario e pu\u00f2 essere revocato in qualsiasi momento senza necessit\u00e0 di fornire motivazioni. \u00c8 possibile inviare la revoca all\u2019indirizzo <a href=\"mailto:info@wassermann-technologie.de\">info@wassermann-technologie.de<\/a>. Ulteriori informazioni sulla protezione dei dati sono disponibili <a href=\"https:\/\/wassermann-automation.com\/datenschutz\/\" target=\"_blank\">qui<\/a>.<\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"col lg_12\">\n\t<p><span id=\"wpcf7-6a97b8d018a61-wrapper\" class=\"wpcf7-form-control-wrap cf7apps-honeypot-wrap honeypot-491-wrap\" data-cf7apps-honeypot=\"honeypot-491\" style=\"position:absolute;width:1px;height:1px;padding:0;margin:-1px;overflow:hidden;clip:rect(0,0,0,0);white-space:nowrap;border:0;\"><input type=\"hidden\" name=\"honeypot-491-random-hash\" value=\"20260902\"><input type=\"hidden\" name=\"honeypot-491-time-token\" value=\"MTc4ODMyODE0NA==.e41aa249406e7765867482bd045fba33dad50f6f24ba2cb4a6c5ef0889c97601\"><label\n\t\t    for=\"wpcf7-6a97b8d018a61-field\"\n\t\t    class=\"hp-message\"\n        >Si prega di lasciare vuoto questo campo.<\/label><input\n\t    id=\"wpcf7-6a97b8d018a61-field\"\n\t    \n\t    class=\"wpcf7-form-control wpcf7-text\"\n\t    type=\"text\"\n\t    name=\"9nsuhwtadhtr\"\n\t    value=\"\"\n\t    autocomplete=\"off\"\n\t    tabindex=\"1000\"\n\t    data-cf7apps-tabindex=\"1000\"\n    \/><\/span><input class=\"wpcf7-form-control wpcf7-submit has-spinner button outline blue\" type=\"submit\" value=\"Invia\" \/>\n\t<\/p>\n<\/div>\n<p class=\"col lg_12\"><small>I campi contrassegnati con * sono obbligatori.<\/small>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n            <\/div>\r\n          <\/div>\r\n\r\n          <!-- Individuelle Produktkonfiguration starten? -->\r\n          <div class=\"filter-accordion_entry accordion_entry\" id=\"configuration-accordion\">\r\n            <a href=\"#\" class=\"headline\" role=\"button\" id=\"faq_toggler__1\" aria-controls=\"faq_content__1\" aria-expanded=\"true\" class=\"headline active\">\r\n              <p class=\"h3 headline\">\r\n                Avviare una configurazione personalizzata del prodotto?              <\/p>\r\n            <\/a>\r\n            <div class=\"filter-accordion_content accordion_content\" style=\"display: none;\">\r\n              \r\n<form class=\"product_request \">\r\n\r\n    <input type=\"hidden\" name=\"baseurl\" value=\"https:\/\/wassermann-automation.com\/wp-content\/themes\/wassermann\">\r\n  <input type=\"hidden\" name=\"product\" value=\"TOOL-D No.XXX\">\r\n  <input type=\"hidden\" name=\"permalink\" value=\"https:\/\/wassermann-group.com\/it\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\/werkzeugspeicher-tool-d\/\">\r\n  <input type=\"hidden\" name=\"lang\" value=\"it\">\r\n  <!-- <fieldset> -->\r\n    <span class=\"cp-honeypot-wrap\" style=\"display:none !important; visibility:hidden !important;\">\r\n      <input id=\"hp-6a97b8d01c3e3\" class=\"text-input\" type=\"text\" name=\"hp-42\" value=\"\"\r\n        size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\">\r\n    <\/span>\r\n  <!-- <\/fieldset> -->\r\n\r\n\r\n      \r\n<div class=\"filter-options filter-options-container\">      <div class=\"multi-selector \">\r\n\r\n\r\n        \r\n\r\n        <div class=\"select-field\">\r\n          <input type=\"text\" name=\"filter_1002\"\r\n            placeholder=\"storage architecture\" id=\"\" class=\"input-selector\" disabled>\r\n          <span class=\"down-arrow\"><i class=\"arrow down\"><\/i><\/span>\r\n        <\/div>\r\n        <!-- List of checkboxes and options -->\r\n        <div class=\"list\">\r\n          <div class=\"list-items\">\r\n                          <label for=\"1003\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"1003\"\r\n                  name=\"Compact circular storage system\" id=\"1003\">\r\n                Compact circular storage system              <\/label>\r\n                          <label for=\"1004\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"1004\"\r\n                  name=\"Expandable linear storage system\" id=\"1004\">\r\n                Expandable linear storage system              <\/label>\r\n            \r\n          <\/div>\r\n          <div class=\"resetfilter\">\r\n            <a href=\"\" class=\"reset\">\r\n              Azzeramento della selezione            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>        <div class=\"select-break\">&nbsp;<\/div>\r\n      <div class=\"slider-selector \" type=\"range\"\r\n        name=\"filter_852\" placeholder=\"Number of tools:\"\r\n        data-min=\"0\" data-max=\"999999\"\r\n        data-id=\"852\"\r\n        data-unit=\"pcs.\"\r\n        data-slider-stepwidth=\"1\">\r\n        <label>Number of tools:<\/label>\r\n        <div class=\"slider\"><\/div>\r\n        <div class=\"min-max-values\">\r\n          <span>0            pcs.<\/span>\r\n          <span>999999            pcs.<\/span>\r\n        <\/div>\r\n      <\/div>\r\n            <div class=\"multi-selector \">\r\n\r\n\r\n        \r\n\r\n        <div class=\"select-field\">\r\n          <input type=\"text\" name=\"filter_845\"\r\n            placeholder=\"Tool holder\" id=\"\" class=\"input-selector\" disabled>\r\n          <span class=\"down-arrow\"><i class=\"arrow down\"><\/i><\/span>\r\n        <\/div>\r\n        <!-- List of checkboxes and options -->\r\n        <div class=\"list\">\r\n          <div class=\"list-items\">\r\n                          <label for=\"883\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"883\"\r\n                  name=\"Capto C10\" id=\"883\">\r\n                Capto C10              <\/label>\r\n                          <label for=\"884\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"884\"\r\n                  name=\"SK 40\" id=\"884\">\r\n                SK 40              <\/label>\r\n                          <label for=\"885\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"885\"\r\n                  name=\"SK50\" id=\"885\">\r\n                SK50              <\/label>\r\n                          <label for=\"870\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"870\"\r\n                  name=\"HSK 25\" id=\"870\">\r\n                HSK 25              <\/label>\r\n                          <label for=\"886\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"886\"\r\n                  name=\"BT 40\" id=\"886\">\r\n                BT 40              <\/label>\r\n                          <label for=\"871\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"871\"\r\n                  name=\"HSK 32\" id=\"871\">\r\n                HSK 32              <\/label>\r\n                          <label for=\"887\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"887\"\r\n                  name=\"BT 50\" id=\"887\">\r\n                BT 50              <\/label>\r\n                          <label for=\"967\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"967\"\r\n                  name=\"All common\" id=\"967\">\r\n                All common              <\/label>\r\n                          <label for=\"872\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"872\"\r\n                  name=\"HSK 50\" id=\"872\">\r\n                HSK 50              <\/label>\r\n                          <label for=\"888\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"888\"\r\n                  name=\"ISO\" id=\"888\">\r\n                ISO              <\/label>\r\n                          <label for=\"873\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"873\"\r\n                  name=\"HSK 40\" id=\"873\">\r\n                HSK 40              <\/label>\r\n                          <label for=\"889\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"889\"\r\n                  name=\"KM 100\" id=\"889\">\r\n                KM 100              <\/label>\r\n                          <label for=\"874\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"874\"\r\n                  name=\"HSK 63\" id=\"874\">\r\n                HSK 63              <\/label>\r\n                          <label for=\"875\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"875\"\r\n                  name=\"HSK-A63\" id=\"875\">\r\n                HSK-A63              <\/label>\r\n                          <label for=\"876\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"876\"\r\n                  name=\"HSK 80\" id=\"876\">\r\n                HSK 80              <\/label>\r\n                          <label for=\"877\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"877\"\r\n                  name=\"HSK 100\" id=\"877\">\r\n                HSK 100              <\/label>\r\n                          <label for=\"1005\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"1005\"\r\n                  name=\"HSK 125\" id=\"1005\">\r\n                HSK 125              <\/label>\r\n                          <label for=\"878\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"878\"\r\n                  name=\"HSK-A100\" id=\"878\">\r\n                HSK-A100              <\/label>\r\n                          <label for=\"879\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"879\"\r\n                  name=\"Capto C4\" id=\"879\">\r\n                Capto C4              <\/label>\r\n                          <label for=\"880\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"880\"\r\n                  name=\"Capto C5\" id=\"880\">\r\n                Capto C5              <\/label>\r\n                          <label for=\"881\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"881\"\r\n                  name=\"Capto C6\" id=\"881\">\r\n                Capto C6              <\/label>\r\n                          <label for=\"882\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"882\"\r\n                  name=\"Capto C8\" id=\"882\">\r\n                Capto C8              <\/label>\r\n            \r\n          <\/div>\r\n          <div class=\"resetfilter\">\r\n            <a href=\"\" class=\"reset\">\r\n              Azzeramento della selezione            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>        <div class=\"select-break\">&nbsp;<\/div>\r\n      <div class=\"slider-selector \" type=\"range\"\r\n        name=\"filter_847\" placeholder=\"max. tool diameter\"\r\n        data-min=\"0\" data-max=\"999999\"\r\n        data-id=\"847\"\r\n        data-unit=\"mm\"\r\n        data-slider-stepwidth=\"10\">\r\n        <label>max. tool diameter<\/label>\r\n        <div class=\"slider\"><\/div>\r\n        <div class=\"min-max-values\">\r\n          <span>0            mm<\/span>\r\n          <span>999999            mm<\/span>\r\n        <\/div>\r\n      <\/div>\r\n            <div class=\"select-break\">&nbsp;<\/div>\r\n      <div class=\"slider-selector \" type=\"range\"\r\n        name=\"filter_846\" placeholder=\"max. tool length\"\r\n        data-min=\"0\" data-max=\"999999\"\r\n        data-id=\"846\"\r\n        data-unit=\"mm\"\r\n        data-slider-stepwidth=\"1\">\r\n        <label>max. tool length<\/label>\r\n        <div class=\"slider\"><\/div>\r\n        <div class=\"min-max-values\">\r\n          <span>0            mm<\/span>\r\n          <span>999999            mm<\/span>\r\n        <\/div>\r\n      <\/div>\r\n            <div class=\"select-break\">&nbsp;<\/div>\r\n      <div class=\"slider-selector \" type=\"range\"\r\n        name=\"filter_844\" placeholder=\"Tool weights\"\r\n        data-min=\"0\" data-max=\"999999\"\r\n        data-id=\"844\"\r\n        data-unit=\"kg\"\r\n        data-slider-stepwidth=\"1\">\r\n        <label>Tool weights<\/label>\r\n        <div class=\"slider\"><\/div>\r\n        <div class=\"min-max-values\">\r\n          <span>0            kg<\/span>\r\n          <span>999999            kg<\/span>\r\n        <\/div>\r\n      <\/div>\r\n            <div class=\"select-break\">&nbsp;<\/div>\r\n      <div class=\"slider-selector \" type=\"range\"\r\n        name=\"filter_987\" placeholder=\"Footprint\"\r\n        data-min=\"0\" data-max=\"999999\"\r\n        data-id=\"987\"\r\n        data-unit=\"m\u00b2\"\r\n        data-slider-stepwidth=\"0.1\">\r\n        <label>Footprint<\/label>\r\n        <div class=\"slider\"><\/div>\r\n        <div class=\"min-max-values\">\r\n          <span>0            m\u00b2<\/span>\r\n          <span>999999            m\u00b2<\/span>\r\n        <\/div>\r\n      <\/div>\r\n            <div class=\"select-break\">&nbsp;<\/div>\r\n      <div class=\"slider-selector \" type=\"range\"\r\n        name=\"filter_859\" placeholder=\"Dimensions - depth\"\r\n        data-min=\"0\" data-max=\"999999\"\r\n        data-id=\"859\"\r\n        data-unit=\"mm\"\r\n        data-slider-stepwidth=\"10\">\r\n        <label>Dimensions &#8211; depth<\/label>\r\n        <div class=\"slider\"><\/div>\r\n        <div class=\"min-max-values\">\r\n          <span>0            mm<\/span>\r\n          <span>999999            mm<\/span>\r\n        <\/div>\r\n      <\/div>\r\n            <div class=\"select-break\">&nbsp;<\/div>\r\n      <div class=\"slider-selector \" type=\"range\"\r\n        name=\"filter_860\" placeholder=\"Dimensions - width\"\r\n        data-min=\"0\" data-max=\"999999\"\r\n        data-id=\"860\"\r\n        data-unit=\"mm\"\r\n        data-slider-stepwidth=\"10\">\r\n        <label>Dimensions &#8211; width<\/label>\r\n        <div class=\"slider\"><\/div>\r\n        <div class=\"min-max-values\">\r\n          <span>0            mm<\/span>\r\n          <span>999999            mm<\/span>\r\n        <\/div>\r\n      <\/div>\r\n            <div class=\"select-break\">&nbsp;<\/div>\r\n      <div class=\"slider-selector \" type=\"range\"\r\n        name=\"filter_861\" placeholder=\"Dimensions - height\"\r\n        data-min=\"0\" data-max=\"999999\"\r\n        data-id=\"861\"\r\n        data-unit=\"mm\"\r\n        data-slider-stepwidth=\"10\">\r\n        <label>Dimensions &#8211; height<\/label>\r\n        <div class=\"slider\"><\/div>\r\n        <div class=\"min-max-values\">\r\n          <span>0            mm<\/span>\r\n          <span>999999            mm<\/span>\r\n        <\/div>\r\n      <\/div>\r\n            <div class=\"multi-selector \">\r\n\r\n\r\n        \r\n\r\n        <div class=\"select-field\">\r\n          <input type=\"text\" name=\"filter_992\"\r\n            placeholder=\"Terminal control\" id=\"\" class=\"input-selector\" disabled>\r\n          <span class=\"down-arrow\"><i class=\"arrow down\"><\/i><\/span>\r\n        <\/div>\r\n        <!-- List of checkboxes and options -->\r\n        <div class=\"list\">\r\n          <div class=\"list-items\">\r\n                          <label for=\"993\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"993\"\r\n                  name=\"BECKHOFF TwinCAT3\" id=\"993\">\r\n                BECKHOFF TwinCAT3              <\/label>\r\n            \r\n          <\/div>\r\n          <div class=\"resetfilter\">\r\n            <a href=\"\" class=\"reset\">\r\n              Azzeramento della selezione            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>    <\/div>\r\n  \r\n<!-- \/\/CHECKBOXEN -->\r\n  <div class=\"options-container\">\r\n    <b>Opzioni:<\/b>\r\n          <div class=\"checkbox-options\">\r\n        <input type=\"checkbox\" name=\"MULTI-TOOL\" id=\"1011\" value=\"Ja\">\r\n        <label for=\"1011\">MULTI-TOOL<\/label>\r\n                  <span class=\"lg_2 info-wrapper\">\r\n            <div class=\"info-i\">i<\/div>\r\n            <div class=\"tooltip\" id=\"\">\r\n              For fast loading of up to 44 tools simultaneously, parallel with production.            <\/div>\r\n          <\/span>\r\n              <\/div>\r\n          <div class=\"checkbox-options\">\r\n        <input type=\"checkbox\" name=\"BALLUFF RFID\" id=\"1012\" value=\"Ja\">\r\n        <label for=\"1012\">BALLUFF RFID<\/label>\r\n                  <span class=\"lg_2 info-wrapper\">\r\n            <div class=\"info-i\">i<\/div>\r\n            <div class=\"tooltip\" id=\"\">\r\n              Automatic transmission of tool data via RFID            <\/div>\r\n          <\/span>\r\n              <\/div>\r\n      <\/div>\r\n\r\n\r\n  \r\n\r\n  <textarea id=\"message\" name=\"message\" rows=\"4\" cols=\"50\"\r\n    placeholder=\"Non \u00e8 quello giusto per lei? Ci comunichi le sue esigenze. \"><\/textarea>\r\n\r\n\r\n  \r\n        <div class=\"basic_options_data filter-options\">\r\n  <p class=\"h3 headline\">\r\n    Trasmettere i dati di base sulla macchina utensile  <\/p>\r\n  <fieldset class=\"col lg_6\">\r\n    <span>Produttore<\/span>\r\n    <span class=\"wpcf7-form-control-wrap\">\r\n      <input type=\"text\" name=\"manufacturer\" placeholder=\"\" value=\"\" size=\"40\"\r\n        class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\"\r\n        aria-required=\"true\" aria-invalid=\"false\">\r\n    <\/span>\r\n  <\/fieldset>\r\n  <fieldset class=\"col lg_6\">\r\n    <span>Tipo<\/span>\r\n    <span class=\"wpcf7-form-control-wrap\">\r\n      <input type=\"text\" name=\"type\" placeholder=\"\" value=\"\" size=\"40\"\r\n        class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\"\r\n        aria-required=\"true\" aria-invalid=\"false\">\r\n    <\/span>\r\n  <\/fieldset>\r\n\r\n  <fieldset class=\"col lg_6\">\r\n    <span>Controllo incl versione<\/span>\r\n    <span class=\"wpcf7-form-control-wrap\">\r\n      <input type=\"text\" name=\"control\" placeholder=\"\" value=\"\" size=\"40\"\r\n        class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\"\r\n        aria-required=\"true\" aria-invalid=\"false\">\r\n    <\/span>\r\n  <\/fieldset>\r\n\r\n  <div class=\"basic_options-container\">\r\n      <\/div>\r\n<\/div>      \r\n\r\n  <div class=\"contact_data\">\r\n    <p class=\"h3 headline\">Dettagli di contatto<\/p>\r\n    <fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"153045\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f153045-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset><fieldset class=\"col lg_6\">\n\t<p><span>Nome*<\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"your-firstname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-firstname\" \/><\/span>\n\t<\/p>\n<\/fieldset><fieldset class=\"col lg_6\">\n\t<p><span>Nome*<\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t<\/p>\n<\/fieldset><fieldset class=\"col lg_6\">\n\t<p><span>Azienda<\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"company\" \/><\/span>\n\t<\/p>\n<\/fieldset><fieldset class=\"col lg_6\">\n\t<p><span>Indirizzo e-mail*<\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n<\/fieldset><fieldset class=\"col lg_12\">\n\t<p><span>Messaggio<\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"message_form\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"message_form\"><\/textarea><\/span>\n\t<\/p>\n<\/fieldset><fieldset class=\"col lg_12 checkbox\">\n\t<p>Dopo aver inviato il modulo, i miei dati saranno utilizzati per elaborare e rispondere alla mia richiesta. Ho preso nota delle <a href=\"https:\/\/wassermann-automation.com\/datenschutz\/\" target=\"_blank\">informazioni sulla protezione dei dati<\/a>.\n\t<\/p>\n<\/fieldset><fieldset class=\"col lg_12 checkbox\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"kontakt\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"kontakt[]\" value=\"S\u00ec\" \/><span class=\"wpcf7-list-item-label\">S\u00ec<\/span><\/span><\/span><\/span>\n\t<\/p>\n\t<p>Acconsento a che la WASSERMANN TECHNOLOGIE GmbH tratti regolarmente i miei dati per l\u2019invio di una newsletter via e-mail (informazioni su offerte, promozioni, prodotti e servizi della WASSERMANN TECHNOLOGIE GmbH). Il presente consenso \u00e8 volontario e pu\u00f2 essere revocato in qualsiasi momento senza necessit\u00e0 di fornire motivazioni. \u00c8 possibile inviare la revoca all\u2019indirizzo <a href=\"mailto:info@wassermann-technologie.de\">info@wassermann-technologie.de<\/a>. Ulteriori informazioni sulla protezione dei dati sono disponibili <a href=\"https:\/\/wassermann-automation.com\/datenschutz\/\" target=\"_blank\">qui<\/a>.\n\t<\/p>\n<\/fieldset>  <\/div>\r\n\r\n  <fieldset>\r\n    <input type=\"submit\" class=\"button product_submit outline blue\"\r\n      value=\"Inviare\">\r\n  <\/fieldset>\r\n  <input type=\"hidden\" class=\"redirect\" value=\"https:\/\/wassermann-automation.com\/it\/vielen-dank-anfrage\/\">\r\n  <p class=\"col lg_12\" style=\"margin-top: 1rem\">\r\n    <small>I campi contrassegnati con * sono obbligatori.<\/small>\r\n  <\/p>\r\n  <div id=\"error_message_block\"><\/div>\r\n  <div id=\"success_message_block\" style=\"display:none\">\r\n    Grazie per il suo messaggio! La ricontatteremo a breve.   <\/div>\r\n\r\n<\/form>            <\/div>\r\n          <\/div>\r\n\r\n        <\/div>\r\n        <!-- END Akkordion -->        \r\n<div class=\"button-controll-wrapper\" style=\"display: none;\">\r\n          <a href=\"#\" class=\"opendialog button blue outline\">\r\n            Richiesta di configurazione          <\/a>\r\n        <\/div>              <\/div>\n      <!-- END Filter -->\n    <\/div>\n    <!-- END Table -->\n  <\/div>\n  <!-- END config -->\n\n<\/div>\n  <!-- END col -->\n<\/div>\n<!-- END filter_Blick -->\n\r\n    <!-- SEO -->\n  \n  <div class=\"seo_textblock wassermann_block  grey_background\" data-source=\"160268\">\n    <!--<h2 class=\"custom_headline h1\" class=\"custom_headline h1\" id=\"terminali-utensili-automazione-cnc-di-wassermann-soluzioni-personalizzate-per-la-sua-produzione\">TERMINALI UTENSILI<\/h2>-->\n\n    <div>\n      \r\n\r\n<div id=\"block-657a17282f4f3\"  class=\"headline_icon wassermann_block\">\r\n  <div class=\"noborder\">\r\n        <h2 class=\"custom_headline h2\" class=\"custom_headline h2\" id=\"automazione-cnc-di-wassermann-soluzioni-personalizzate-per-la-sua-produzione\">\r\n              <span class=\"headline\">Automazione CNC di Wassermann<\/span>\r\n                    <strong class=\"subline\">Soluzioni personalizzate per la sua produzione<\/strong>\r\n          <\/h2>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"accordion-container accordion-block accordion-multi wassermann_block\">\r\n<!--\r\n    <div class=\"controlls\">\r\n        <a href=\"#\" class=\"button openall\">\r\n            <div class=\"closeall\" style=\"display:none\">\r\n                Chiudere tutti            <\/div>\r\n\r\n            <div class=\"openall\">\r\n                Aprire tutti            <\/div>\r\n\r\n        <\/a>\r\n    <\/div> -->\r\n\r\n        <div class=\"accordion_entry\">\r\n        <a href=\"#\" role=\"button\" id=\"faq_toggler_block_2ec542b7c7a2c40e8ea1c67359c28c4c_1\" aria-controls=\"faq_content_block_2ec542b7c7a2c40e8ea1c67359c28c4c_1\" aria-expanded=\"false\" class=\"headline \">\r\n            <h3 class=\"custom_headline h3 font-light\"  class=\"custom_headline h3 font-light\"  id=\"perche-lautomazione-cnc-per-gli-utensili\">Perch\u00e9 l&#8217;automazione CNC per gli utensili?<\/h3>\r\n        <\/a>\r\n        <div id=\"faq_content_block_2ec542b7c7a2c40e8ea1c67359c28c4c_1\" class=\"accordion_content\" style=\"display:none\">\r\n            <div class=\"col stretch\">\r\n                <div\r\n                    class=\"col   lg_4 md_12  sm_12\">\r\n                                                            <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/09\/90-91-21-443_komp.jpg\" data-featherlight=\"image\">\r\n                        <div class=\"square-box box-shadow lazy\" id=\"child-240\"\r\n                            style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/09\/90-91-21-443_komp.jpg); background-size: cover\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/09\/90-91-21-443_komp-600x600.jpg\" class=\"print_only\" alt=\"\" srcset=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/09\/90-91-21-443_komp-600x600.jpg 600w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/09\/90-91-21-443_komp-150x150.jpg 150w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                            <div class=\"zoom-icon\">\r\n                                <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\"\r\n                                    alt=\"zoom\" width=\"40px\" height=\"40px\">\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                                                        <\/div>\r\n                \r\n                <div\r\n                    class=\"col   lg_8 md_12  sm_12\">\r\n                    <div class=\"content\">\r\n                        <div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"71cdad01-17ea-4428-8552-69d0ddce4d40\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p><strong>L&#8217;insufficiente stoccaggio degli utensili riduce la produttivit\u00e0<\/strong><\/p>\n<p>Un magazzino utensili troppo piccolo pu\u00f2 limitare la produttivit\u00e0 e rendere pi\u00f9 difficile il percorso verso la produzione non presidiata. Con un terminale TOOL, pu\u00f2 espandere il magazzino della macchina da 200 a 1000 utensili, superando le limitazioni tecniche ed eliminando gli ostacoli al successo. <\/p>\n<p>I nostri terminali TOOL ottimizzano la gestione degli utensili caricando gli utensili per i prossimi ordini nel magazzino interno della macchina mentre la produzione \u00e8 ancora in corso. Ci\u00f2 avviene in modo efficiente in base alla frequenza di utilizzo degli utensili, il che significa che gli spazi liberi del magazzino sono sempre riempiti in modo sensato. <\/p>\n<p>A proposito: non \u00e8 necessario rivolgersi al costruttore della macchina per adattare il sistema di gestione degli utensili al sistema di controllo della macchina &#8211; i nostri esperti fanno dialogare il software e il sistema di controllo.<\/p>\n<p><strong>I sistemi di automazione CNC sono la chiave per trasformare il processo di produzione.<\/strong><\/p>\n<p>Wassermann utilizza tecnologie innovative per portare i sistemi di automazione CNC standardizzati ad un nuovo livello. Le nostre soluzioni riducono al minimo la movimentazione manuale degli utensili, garantiscono la precisione e offrono vantaggi in termini di tempi di allestimento e di funzionamento della macchina. <\/p>\n<p>I vantaggi dei nostri sistemi di automazione CNC in sintesi:<\/p>\n<ul>\n<li><strong>Maggiore produttivit\u00e0 &#8211; <\/strong> Aumenta l&#8217;efficienza produttiva e la produzione con l&#8217;automazione CNC che ottimizza la movimentazione dei materiali.<\/li>\n<li><strong>Pi\u00f9 ore di mandrino<\/strong> &#8211; Utilizzo ottimale della capacit\u00e0 della macchina e produzione non presidiata per periodi pi\u00f9 lunghi.<\/li>\n<li><strong>Margini migliori &#8211;<\/strong> ottimizza la redditivit\u00e0 attraverso un&#8217;efficiente automazione CNC e riduce i costi.<\/li>\n<li><strong>Nessuna dimensione di lotto &#8211;<\/strong> lavoro efficiente a partire dalla dimensione di lotto 1, grazie a soluzioni flessibili di automazione CNC.<\/li>\n<li><strong>Ridurre la carenza di manodopera qualificata<\/strong> &#8211; Creare luoghi di lavoro moderni e modelli di turni flessibili, sollevando i dipendenti dai compiti manuali.<\/li>\n<\/ul>\n<p>Scopra il futuro dell&#8217;automazione CNC con Wassermann e aumenti l&#8217;efficienza e la competitivit\u00e0 della sua azienda.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mt-1 flex justify-start gap-3 empty:hidden\">\n<div class=\"text-gray-400 flex self-end lg:self-center justify-center lg:justify-start mt-0 gap-1 visible\"><\/div>\n<\/div>\n                                                <div class=\"button-controll-wrapper\">\r\n\r\n                            \r\n                            <div class=\"button-wrapper\">\r\n                                <a href=\"https:\/\/calendly.com\/wt-sauth\" class=\"button blue outline\" target=\"_blank\">\r\n                                                                        <span>Prenoti un appuntamento di consulenza  <\/span>\r\n                                                                                                        <\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <\/div>\r\n\r\n                <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n        <div class=\"accordion_entry\">\r\n        <a href=\"#\" role=\"button\" id=\"faq_toggler_block_2ec542b7c7a2c40e8ea1c67359c28c4c_2\" aria-controls=\"faq_content_block_2ec542b7c7a2c40e8ea1c67359c28c4c_2\" aria-expanded=\"false\" class=\"headline \">\r\n            <h3 class=\"custom_headline h3 font-light\" >Soluzioni di automazione CNC sensibili per gli utensili<\/h3>\r\n        <\/a>\r\n        <div id=\"faq_content_block_2ec542b7c7a2c40e8ea1c67359c28c4c_2\" class=\"accordion_content\" style=\"display:none\">\r\n            <div class=\"col stretch\">\r\n                <div\r\n                    class=\"col   lg_4 md_12  sm_12\">\r\n                                                            <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Greifer-eingefahren-4274.jpg\" data-featherlight=\"image\">\r\n                        <div class=\"square-box box-shadow lazy\" id=\"child-240\"\r\n                            style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Greifer-eingefahren-4274.jpg); background-size: cover\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Greifer-eingefahren-4274-600x600.jpg\" class=\"print_only\" alt=\"\" srcset=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Greifer-eingefahren-4274-600x600.jpg 600w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Greifer-eingefahren-4274-150x150.jpg 150w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                            <div class=\"zoom-icon\">\r\n                                <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\"\r\n                                    alt=\"zoom\" width=\"40px\" height=\"40px\">\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                                                        <\/div>\r\n                \r\n                <div\r\n                    class=\"col   lg_8 md_12  sm_12\">\r\n                    <div class=\"content\">\r\n                        <div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"5bf43d33-6ed6-40d5-80bd-986a1f01b85f\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p><strong>In esclusiva da noi: il negozio di utensili brevettato.<\/strong><\/p>\n<p>Per massimizzare la densit\u00e0 di imballaggio, abbiamo sviluppato un concetto di stoccaggio brevettato per i nostri TOOL-TERMINALS. Uno speciale sistema di tamburi consente una densit\u00e0 di utensili che soluzioni analoghe non possono raggiungere a parit\u00e0 di ingombro. <\/p>\n<p><strong>Dalla prova di concetto al successo in sole 12 settimane<\/strong><\/p>\n<p>Nel 2013, \u00e8 nata l&#8217;idea di sviluppare una nuova soluzione per lo stoccaggio e l&#8217;automazione degli utensili. Dopo appena 12 settimane, la prova di concetto era pronta nel nostro stabilimento di produzione &#8211; sviluppata, prodotta, assemblata e commissionata da WASSERMANN. Il prototipo \u00e8 tuttora attivo nella nostra produzione e rifornisce ogni giorno una delle nostre macchine utensili.  <\/p>\n<p><strong>Ci distinguiamo per le soluzioni di automazione CNC mirate.<\/strong><\/p>\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"c02ec800-95f5-46ea-bad1-ecec384cef05\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>Con decenni di esperienza come macchinisti CNC, capiamo esattamente cosa guida la sua produzione CNC e lavoriamo in modo specifico sulle sue esigenze specifiche. Pu\u00f2 contare su soluzioni personalizzate, a lungo termine e affidabili. <\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>Con oltre 30 macchine utensili in funzione, non solo comprendiamo le sue preoccupazioni tecniche, ma anche i suoi requisiti operativi. Con Wassermann aumenta l&#8217;efficienza, riduce i costi di investimento e abbrevia il periodo di ammortamento. Si affidi a Wassermann per aumentare la sua produttivit\u00e0 con i sistemi di automazione CNC e ottimizzare la sua produzione.  <\/p>\n<p>Wassermann \u00e8 sinonimo di soluzioni su misura: dalla modernizzazione dei macchinari all&#8217;ottimizzazione dei processi esistenti, offriamo un&#8217;automazione CNC perfetta.<\/p>\n<p><strong>Scelga uno specialista dell&#8217;automazione CNC che non solo sviluppa, ma anche produce quotidianamente.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n                                                <div class=\"button-controll-wrapper\">\r\n\r\n                            \r\n                            <div class=\"button-wrapper\">\r\n                                <a href=\"https:\/\/wassermann-group.com\/it\/ueber-wassermann\/fertigung\/\" class=\"button blue outline\" target=\"_blank\">\r\n                                                                        <span>Produzione CNC presso Wassermann<\/span>\r\n                                                                                                        <\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <\/div>\r\n\r\n                <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n        <div class=\"accordion_entry\">\r\n        <a href=\"#\" role=\"button\" id=\"faq_toggler_block_2ec542b7c7a2c40e8ea1c67359c28c4c_3\" aria-controls=\"faq_content_block_2ec542b7c7a2c40e8ea1c67359c28c4c_3\" aria-expanded=\"false\" class=\"headline \">\r\n            <h3 class=\"custom_headline h3 font-light\" >Gestione economica degli utensili con l&#8217;automazione CNC<\/h3>\r\n        <\/a>\r\n        <div id=\"faq_content_block_2ec542b7c7a2c40e8ea1c67359c28c4c_3\" class=\"accordion_content\" style=\"display:none\">\r\n            <div class=\"col stretch\">\r\n                <div\r\n                    class=\"col   lg_4 md_12  sm_12\">\r\n                                                            <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409.jpg\" data-featherlight=\"image\">\r\n                        <div class=\"square-box box-shadow lazy\" id=\"child-240\"\r\n                            style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409.jpg); background-size: cover\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"421\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409.jpg\" class=\"print_only\" alt=\"\" srcset=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409.jpg 2362w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409-250x176.jpg 250w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409-700x492.jpg 700w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409-768x539.jpg 768w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409-1536x1079.jpg 1536w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409-2048x1438.jpg 2048w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409-142x100.jpg 142w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409-120x84.jpg 120w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409-1920x1349.jpg 1920w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                            <div class=\"zoom-icon\">\r\n                                <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\"\r\n                                    alt=\"zoom\" width=\"40px\" height=\"40px\">\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                                                        <\/div>\r\n                \r\n                <div\r\n                    class=\"col   lg_8 md_12  sm_12\">\r\n                    <div class=\"content\">\r\n                        <div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"ef018243-454d-4bdf-a2d3-1908b25a7a2f\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p><strong>UTENSILI-TERMINALI per la sua produzione CNC flessibile<\/strong><\/p>\n<p>I nostri TOOL-TERMINALS offrono un&#8217;elevata densit\u00e0 di imballaggio degli utensili e si adattano facilmente a qualsiasi capannone di produzione. La griglia di altezza integrata offre la massima flessibilit\u00e0, anche con altezze insolite dei capannoni. Le posizioni di stoccaggio si adattano alla variet\u00e0 di tipi di utensili e i nostri concetti di trasferimento sono preparati per diversi design di magazzino utensili.  <\/p>\n<p>Non pensiamo solo a soluzioni tecniche, ma anche a concetti ben studiati. Il numero e il tipo di macchine utensili collegate a un TOOL-TERMINAL possono cambiare nel tempo, senza sorprese sulle interfacce. Abbiamo gi\u00e0 collegato con successo molti terminali a macchine esistenti e nuove.  <\/p>\n<p>I nostri utensili-TERMINALI si armonizzano perfettamente con la sua produzione CNC.<\/p>\n<p><strong>Aumento della produttivit\u00e0 senza nuovi acquisti grazie all&#8217;automazione CNC<br \/>\n<\/strong><\/p>\n<p>L&#8217;acquisto di una nuova macchina utensile con un magazzino utensili pi\u00f9 grande non \u00e8 l&#8217;unica opzione per aumentare la produttivit\u00e0. Noi di Wassermann la incoraggiamo a verificare se la sua macchina esistente pu\u00f2 essere adattata con sistemi di automazione CNC standardizzati per gli utensili. Questo \u00e8 spesso il modo pi\u00f9 conveniente per ottenere maggiori prestazioni dal macchinario esistente.  <\/p>\n<p>Nella pratica di lavorazione complessa, offriamo soluzioni per diversi produttori di macchine e condizioni di spazio limitate.<\/p>\n<p><strong>Perch\u00e9 automatizzare le macchine esistenti?<\/strong><\/p>\n<p>Le macchine esistenti spesso offrono una qualit\u00e0 di produzione di prima classe e sono tecnicamente all&#8217;avanguardia. L&#8217;automazione CNC mirata degli utensili e\/o dei pezzi, grazie ai sistemi di automazione CNC, consente di aumentare la produttivit\u00e0 senza compromettere la qualit\u00e0 della produzione. <\/p>\n<p><strong>Soluzioni personalizzate per la sua produzione<\/strong><\/p>\n<p>Wassermann le offre soluzioni personalizzate che si adattano esattamente alla sua configurazione. Questo le consente di ottenere il massimo vantaggio in termini di efficienza, investimento e ammortamento. Le nostre soluzioni portano la sua produzione ad un livello superiore e ci concentriamo sulla soddisfazione delle sue esigenze.  <\/p>\n<p><strong>Con Wassermann e la nostra automazione CNC, non solo guadagna produttivit\u00e0, ma d\u00e0 anche forma al futuro della sua produzione.<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mt-1 flex justify-start gap-3 empty:hidden\">\n<div class=\"text-gray-400 flex self-end lg:self-center justify-center lg:justify-start mt-0 gap-1 visible\"><\/div>\n<\/div>\n                                                <div class=\"button-controll-wrapper\">\r\n\r\n                            \r\n                            <div class=\"button-wrapper\">\r\n                                <a href=\"https:\/\/calendly.com\/wt-sauth\" class=\"button blue outline\" target=\"_blank\">\r\n                                                                        <span>Prenoti un appuntamento di consulenza<\/span>\r\n                                                                                                        <\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <\/div>\r\n\r\n                <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n    \r\n<\/div>\r\n    <\/div>\n  <\/div>\n\n<!-- SEO ENDE -->\r\n","protected":false},"excerpt":{"rendered":"<p>Numero di utensili: 600<br \/>\nDiametro utensile: max. 280 mm<br \/>\nLunghezza utensile: max. 500 mm<br \/>\nPeso utensile: max. 25 kg  <\/p>\n","protected":false},"featured_media":156418,"menu_order":0,"template":"","products_option":[],"products_category":[1259,1260,1261,1262],"product_asset":[1258],"products_filter":[],"class_list":["post-160268","products","type-products","status-publish","has-post-thumbnail","hentry","products_category-automazione-per-i-macchinisti","products_category-terminali-degli-strumenti","products_category-macchine-utensili-automazione-per-oem","products_category-terminali-oem-tool","product_asset-sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Automazione CNC: Stoccaggio utensili D<\/title>\n<meta name=\"description\" content=\"Automazione di macchine CNC, utensili e pezzi - Stoccaggio utensili D \u25ba Consultazione online\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wassermann-automation.com\/it\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\/werkzeugspeicher-tool-d\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Automazione CNC: Stoccaggio utensili D\" \/>\n<meta property=\"og:description\" content=\"Automazione di macchine CNC, utensili e pezzi - Stoccaggio utensili D \u25ba Consultazione online\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wassermann-group.com\/it\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\/werkzeugspeicher-tool-d\/\" \/>\n<meta property=\"og:site_name\" content=\"Wassermann Technologie GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-28T11:18:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2025\/08\/Tool-D.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\\\/werkzeugspeicher-tool-d\\\/\",\"url\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\\\/werkzeugspeicher-tool-d\\\/\",\"name\":\"Automazione CNC: Stoccaggio utensili D\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/NEW\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\\\/werkzeugspeicher-tool-d\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\\\/werkzeugspeicher-tool-d\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wassermann-automation.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Tool-D.png\",\"datePublished\":\"2023-01-20T10:43:14+00:00\",\"dateModified\":\"2026-05-28T11:18:39+00:00\",\"description\":\"Automazione di macchine CNC, utensili e pezzi - Stoccaggio utensili D \u25ba Consultazione online\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\\\/werkzeugspeicher-tool-d\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wassermann-group.com\\\/it\\\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\\\/werkzeugspeicher-tool-d\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\\\/werkzeugspeicher-tool-d\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wassermann-automation.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Tool-D.png\",\"contentUrl\":\"https:\\\/\\\/wassermann-automation.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Tool-D.png\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\\\/werkzeugspeicher-tool-d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TOOL-D No.XXX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/NEW\\\/#website\",\"url\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/NEW\\\/\",\"name\":\"Wassermann Technologie GmbH\",\"description\":\"We think automatically\",\"publisher\":{\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/NEW\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/NEW\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/NEW\\\/#organization\",\"name\":\"Wassermann Technologie GmbH\",\"url\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/NEW\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/NEW\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wassermann-automation.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cropped-WASSERMANN-GROUP.png\",\"contentUrl\":\"https:\\\/\\\/wassermann-automation.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cropped-WASSERMANN-GROUP.png\",\"width\":314,\"height\":276,\"caption\":\"Wassermann Technologie GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/it\\\/NEW\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Automazione CNC: Stoccaggio utensili D","description":"Automazione di macchine CNC, utensili e pezzi - Stoccaggio utensili D \u25ba Consultazione online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wassermann-automation.com\/it\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\/werkzeugspeicher-tool-d\/","og_locale":"it_IT","og_type":"article","og_title":"Automazione CNC: Stoccaggio utensili D","og_description":"Automazione di macchine CNC, utensili e pezzi - Stoccaggio utensili D \u25ba Consultazione online","og_url":"https:\/\/wassermann-group.com\/it\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\/werkzeugspeicher-tool-d\/","og_site_name":"Wassermann Technologie GmbH","article_modified_time":"2026-05-28T11:18:39+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2025\/08\/Tool-D.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wassermann-group.com\/it\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\/werkzeugspeicher-tool-d\/","url":"https:\/\/wassermann-group.com\/it\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\/werkzeugspeicher-tool-d\/","name":"Automazione CNC: Stoccaggio utensili D","isPartOf":{"@id":"https:\/\/wassermann-group.com\/it\/NEW\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wassermann-group.com\/it\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\/werkzeugspeicher-tool-d\/#primaryimage"},"image":{"@id":"https:\/\/wassermann-group.com\/it\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\/werkzeugspeicher-tool-d\/#primaryimage"},"thumbnailUrl":"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2025\/08\/Tool-D.png","datePublished":"2023-01-20T10:43:14+00:00","dateModified":"2026-05-28T11:18:39+00:00","description":"Automazione di macchine CNC, utensili e pezzi - Stoccaggio utensili D \u25ba Consultazione online","breadcrumb":{"@id":"https:\/\/wassermann-group.com\/it\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\/werkzeugspeicher-tool-d\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wassermann-group.com\/it\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\/werkzeugspeicher-tool-d\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/wassermann-group.com\/it\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\/werkzeugspeicher-tool-d\/#primaryimage","url":"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2025\/08\/Tool-D.png","contentUrl":"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2025\/08\/Tool-D.png","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/wassermann-group.com\/it\/sistemi-di-stoccaggio-e-caricamento-utensili-sistemi-di-stoccaggio-e-caricamento-utensili-terminali\/werkzeugspeicher-tool-d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wassermann-group.com\/it\/"},{"@type":"ListItem","position":2,"name":"TOOL-D No.XXX"}]},{"@type":"WebSite","@id":"https:\/\/wassermann-group.com\/it\/NEW\/#website","url":"https:\/\/wassermann-group.com\/it\/NEW\/","name":"Wassermann Technologie GmbH","description":"We think automatically","publisher":{"@id":"https:\/\/wassermann-group.com\/it\/NEW\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wassermann-group.com\/it\/NEW\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/wassermann-group.com\/it\/NEW\/#organization","name":"Wassermann Technologie GmbH","url":"https:\/\/wassermann-group.com\/it\/NEW\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/wassermann-group.com\/it\/NEW\/#\/schema\/logo\/image\/","url":"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2025\/12\/cropped-WASSERMANN-GROUP.png","contentUrl":"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2025\/12\/cropped-WASSERMANN-GROUP.png","width":314,"height":276,"caption":"Wassermann Technologie GmbH"},"image":{"@id":"https:\/\/wassermann-group.com\/it\/NEW\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/wassermann-automation.com\/it\/wp-json\/wp\/v2\/products\/160268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wassermann-automation.com\/it\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/wassermann-automation.com\/it\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":0,"href":"https:\/\/wassermann-automation.com\/it\/wp-json\/wp\/v2\/products\/160268\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wassermann-automation.com\/it\/wp-json\/wp\/v2\/media\/156418"}],"wp:attachment":[{"href":"https:\/\/wassermann-automation.com\/it\/wp-json\/wp\/v2\/media?parent=160268"}],"wp:term":[{"taxonomy":"products_option","embeddable":true,"href":"https:\/\/wassermann-automation.com\/it\/wp-json\/wp\/v2\/products_option?post=160268"},{"taxonomy":"products_category","embeddable":true,"href":"https:\/\/wassermann-automation.com\/it\/wp-json\/wp\/v2\/products_category?post=160268"},{"taxonomy":"product_asset","embeddable":true,"href":"https:\/\/wassermann-automation.com\/it\/wp-json\/wp\/v2\/product_asset?post=160268"},{"taxonomy":"products_filter","embeddable":true,"href":"https:\/\/wassermann-automation.com\/it\/wp-json\/wp\/v2\/products_filter?post=160268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}