{"id":160279,"date":"2023-01-20T11:43:14","date_gmt":"2023-01-20T10:43:14","guid":{"rendered":"https:\/\/wassermann-group.com\/products\/werkzeugspeicher-tool-d\/"},"modified":"2026-05-28T13:18:40","modified_gmt":"2026-05-28T11:18:40","slug":"werkzeugspeicher-tool-d","status":"publish","type":"products","link":"https:\/\/wassermann-group.com\/pt-pt\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\/werkzeugspeicher-tool-d\/","title":{"rendered":"FERRAMENTA-D N.\u00ba XXX"},"content":{"rendered":"\n<!-- BEGIN filter_Blick -->\n<div class=\"filter-block wassermann_block\">\n    <!-- BEGIN col -->\n  <div class=\"col\">\n\n    <!-- BEGIN IMAGES -->\n    <div class=\"col lg_4 md_12  sm_12\">\n          <div class=\"mobile h1 custom_headline\">\r\n        <b><p>Loja de ferramentas TOOL-D<\/p>\n<\/b>\r\n    <\/div>\r\n              <section id=\"main-carousel\" class=\"splide\">\r\n          <div class=\"splide__track\">\r\n            <ul class=\"splide__list\">\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/Tool-D.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/Tool-D-420x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/cnc-automation-werkzeugspeicher-tool-l-zentralmagazin-700x854.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/cnc-automation-werkzeugspeicher-tool-l-zentralmagazin-369x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/06\/cnc-automation-werkzeugspeicher-tool-l-stand-alone-speicher-700x466.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/06\/cnc-automation-werkzeugspeicher-tool-l-stand-alone-speicher-676x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/9561-700x1050.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/9561-scaled.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/cnc-automation-patentierter-werkzeugspeicher-700x467.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/cnc-automation-patentierter-werkzeugspeicher-675x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-1-2.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-1-2-427x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-2-2.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-2-2-612x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-3-2.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-3-2-426x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/0357_1-TOOL-D-700x701.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/0357_1-TOOL-D-450x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                              <li class=\"splide__slide no-animation\">\r\n                  <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/Tool-S.jpg\" data-featherlight=\"image\">\r\n\r\n                    \r\n                    <div class=\"col square-box box-shadow lazy\" id=\"child-240\"\r\n                      style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/Tool-S-420x450.jpg); background-size: cover!important\">\r\n                      <div class=\"zoom-icon\">\r\n                        <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\" alt=\"zoom\"\r\n                          width=\"40px\" height=\"40px\">\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/a>\r\n                <\/li>\r\n                          <\/ul>\r\n          <\/div>\r\n        <\/section>\r\n\r\n        <section id=\"thumbnail-carousel\" class=\"splide\">\r\n          <div class=\"splide__track\">\r\n            <ul class=\"splide__list\">\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/Tool-D-120x128.jpg\" alt=\"\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/cnc-automation-werkzeugspeicher-tool-l-zentralmagazin-120x146.jpg\" alt=\"CNC Automation Werkzeugspeicher TOOL-L Zentralmagazin\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/06\/cnc-automation-werkzeugspeicher-tool-l-stand-alone-speicher-120x80.jpg\" alt=\"CNC Automation Werkzeugspeicher TOOL-L Stand-Alone-Speicher\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/9561-120x180.jpg\" alt=\"\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/cnc-automation-patentierter-werkzeugspeicher-120x80.jpg\" alt=\"CNC Automation patentierter Werkzeugspeicher\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-1-2-120x126.jpg\" alt=\"\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-2-2-120x88.jpg\" alt=\"\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Grafik-3-2-120x127.jpg\" alt=\"\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/0357_1-TOOL-D-120x120.jpg\" alt=\"\">\r\n                <\/li>\r\n                              <li class=\"splide__slide\">\r\n\r\n                  <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2023\/01\/Tool-S-120x128.jpg\" alt=\"\">\r\n                <\/li>\r\n              \r\n            <\/ul>\r\n          <\/div>\r\n        <\/section>\r\n          <\/div>\n    <!-- END IMAGES -->\n\n    <!-- BEGIN DETAILS -->\n    <div class=\"col stretch lg_8 md_12  sm_12\">\n      <div class=\"product_headline_wrapper\">\r\n                  <h1 id=\"loja-de-ferramentas-tool-d-o-milagre-do-espaco-a-ferramenta-terminal-para-o-maximo-desempenho\" id=\"loja-de-ferramentas-tool-d-o-milagre-do-espaco-a-ferramenta-terminal-para-o-maximo-desempenho\">\r\n            <span class=\"headline-desc\"><p>Loja de ferramentas TOOL-D<\/p>\n<\/span>\r\n          <\/h1>\r\n\r\n                                    <h2 class=\"h1 custom_headline table-wrapper\" style=\"margin-top:0\">\r\n                O milagre do espa\u00e7o &#8211; A ferramenta TERMINAL para o m\u00e1ximo desempenho<\/h2>\r\n                                    <\/div>\n      <!-- BEGIN text_content -->\n      <div class=\"table-wrapper \">\n        \r\n    <!-- full -->\r\n            \r\n    <div class=\"content\">\r\n    <p>O nosso TOOL-TERMINAL TOOL-D \u00e9 ideal para ser ligado a todos os tipos de centros de maquina\u00e7\u00e3o, fresadoras e centros de torneamento\/fresagem como um carregador adicional ao seu carregador de m\u00e1quina existente. Gra\u00e7as \u00e0s suas dimens\u00f5es compactas e \u00e0 densidade de embalagem imbat\u00edvel de at\u00e9 550 ferramentas, o TOOL-D pode ser facilmente adaptado a quase todas as m\u00e1quinas existentes. A solu\u00e7\u00e3o tamb\u00e9m \u00e9 ideal como armaz\u00e9m descentralizado ou como armaz\u00e9m de abastecimento para v\u00e1rias m\u00e1quinas em simult\u00e2neo.  <\/p>\n    <\/div>\r\n\n\n                      <p class=\"h3 custom_headline\"><b>Vantagens<\/b><\/p>\r\n          <!-- BEGIN content -->\n          <div class=\"content\">\n            <ul>\n<li class=\"ewa-rteLine\"><strong>Poupan\u00e7a de espa\u00e7o<\/strong> &#8211; elevada densidade de ferramentas, por exemplo, 552 ferramentas em apenas 3,5 m\u00b2<\/li>\n<li class=\"ewa-rteLine\"><strong>Generalista<\/strong>&#8211; para todos os porta-ferramentas comuns<\/li>\n<li class=\"ewa-rteLine\">Armazenamento <strong>aberto<\/strong> com interfaces para gest\u00e3o de ferramentas, pr\u00e9-ajuste de ferramentas e produ\u00e7\u00e3o<\/li>\n<li class=\"ewa-rteLine\"><strong>Produtivo<\/strong> &#8211; reduza os tempos de paragem com moldes irm\u00e3os<\/li>\n<li class=\"ewa-rteLine\"><strong>Personalizado<\/strong> &#8211; tr\u00eas arquitecturas b\u00e1sicas para configura\u00e7\u00f5es flex\u00edveis<\/li>\n<\/ul>\n            \n                          <!-- BEGIN button_wrapper (full) -->\r\n        <div class=\" btn-wrapper-prod\">\r\n\r\n          <div class=\"button-controll-wrapper\">\r\n            <a href=\"#configuration\" class=\"button blue\" title=\"Configurar \"\r\n              id=\"configure-link-accordion\">\r\n              Configura\u00e7\u00e3o personalizada            <\/a>\r\n          <\/div>\r\n\r\n          <div class=\"button-controll-wrapper\">\r\n            <a href=\"#\" class=\"button orange more_mail_prod\" title=\"correio eletr\u00f3nico\"\r\n              data-title=\"Loja de ferramentas TOOL-D\">\r\n              Consulta de produtos            <\/a>\r\n          <\/div>\r\n\r\n\r\n          <div class=\"button-controll-wrapper\">\r\n            <a href=\"#\" class=\"button orange outline compare_select\" data-id=\"160279\"\r\n              title=\"Compare produtos\"\r\n              data-enabled-text=\"Compare produtos\"\r\n              data-disabled-text=\"Remover da compara\u00e7\u00e3o\"\r\n              data-title=\"Loja de ferramentas TOOL-D\">\r\n              Compare produtos            <\/a>\r\n          <\/div>\r\n\r\n        <\/div>\r\n        <!-- END button_wrapper (full) -->            \n                      <\/div>\n          <!-- END content -->\n        \n        \n    <\/div>\n    <!-- END text_content -->\n\n    \n  <\/div>\n  <!-- END DETAILS -->\n\n      \r\n  <!-- \/\/Headline -->\r\n\r\n      <div class=\"col lg_8 md_12 sm_12 no-margin right_headline\">\r\n      <p class=\"h3 custom_headline\" style=\"width:100%\"><b>Informa\u00e7\u00f5es t\u00e9cnicas<\/b>\r\n      <\/p>\r\n    <\/div>\r\n        <!-- BEGIN Modell (full) -->\r\n    <div class=\"col lg_4 md_12 sm_12\">\r\n      <div class=\"\" style=\"width:100%\">\r\n        \r\n        \r\n          \r\n          <div class=\"button-controll-wrapper\">\r\n            \r\n                                                      <div class=\"desc\">\r\n                  <a target=\"_blank\" class=\"\"\r\n                    href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/09\/TOOL-D-Datenblatt_WT_2200905.pdf\">\r\n                    TOOL-D-Datenblatt                  <\/a>\r\n                <\/div>\r\n                                      <div class=\"button-wrapper\">\r\n              <a target=\"_blank\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/09\/TOOL-D-Datenblatt_WT_2200905.pdf\"\r\n                class=\"button outline blue \">\r\n                                  <span>Ficha de dados<\/span>\r\n                              <\/a>\r\n            <\/div>\r\n          <\/div>\r\n              <\/div>\r\n    <\/div>\r\n    <!-- END Modell (full) -->\r\n    <!-- BEGIN table_block -->\r\n  <div class=\"col lg_8 md_12 sm_12\">\r\n    <!-- BEGIN table_wrapper -->\r\n    <div class=\"table-wrapper \">\r\n              <div class=\"table_header\">\r\n          Dados t\u00e9cnicos        <\/div>\r\n      \r\n<!-- BEGIN table -->\r\n<div class=\"table\">\r\n\r\n                  <div class=\"col             \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                storage architecture              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  Compact circular storage system                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col             \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                Number of tools:              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  600 pcs.                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col             \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                Tool holder              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  All common                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col hidden            \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                max. tool diameter              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  280 mm                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col hidden            \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                max. tool length              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  500 mm                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col hidden            \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                Tool weights              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  25 kg                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col hidden            \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                Footprint              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  4.2 m\u00b2                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col hidden            \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                Dimensions &#8211; depth              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  2511 mm                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col hidden            \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                Dimensions &#8211; width              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  1700 mm                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col hidden            \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                Dimensions &#8211; height              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  2967 mm                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                  <div class=\"col hidden            \">\r\n            <div class=\"col headline \">\r\n              <p>\r\n                Terminal control              <\/p>\r\n            <\/div>\r\n            <div class=\"col content\">\r\n                                              <p>\r\n                  BECKHOFF TwinCAT3                <\/p>\r\n                          <\/div>\r\n          <\/div>\r\n                \r\n      <\/div>\r\n    <!-- END table -->\r\n        <a href=\"#\" class=\"more-filter\">Mostrar todos os dados<i class=\"arrow down\"><\/i><\/a>\r\n        <div class=\"button-controll-wrapper\">\r\n          <a href=\"#\" class=\"button orange more_mail_prod\" title=\"correio eletr\u00f3nico\"\r\n            data-title=\"Loja de ferramentas TOOL-D\">\r\n            Consulta de produtos          <\/a>\r\n        <\/div>\r\n          <\/div>\r\n    <!-- END table_wrapper -->\r\n  <\/div>\r\n  <!-- END table_block -->\n          <div class=\"clearfix lg_12 md_12 sm_12\"><\/div>\n      \n      <!-- BEGIN OFFER -->\r\n    <div class=\"lg_4 md_12 sm_12\">\r\n          <\/div>\r\n    <!-- END OFFER -->\r\n  \n  <!-- BEGIN config -->\n  <div class=\"lg_8 md_12 sm_12\">\n    <!-- BEGIN Table -->\n    <div class=\"table-wrapper\" id=\"configuration\">\n              <span class=\"h2 custom_headline\" style=\"display: none;\">\r\n          <p>N\u00e3o tem os par\u00e2metros corretos?<br \/>\n<strong>Personalize agora!<\/strong><\/p>\n        <\/span>\r\n            <!-- BEGIN Filter -->\n      <div class=\"filter \">\n        \r\n<!-- BEGIN Akkordion -->\r\n        <div class=\"filter-accordion-container filter-accordion-block accordion-container accordion-block\">\r\n          <!-- Haben Sie noch Fragen zu dem Produkt? + NEW FORM -->\r\n          <div class=\"filter-accordion_entry accordion_entry\">\r\n            <a href=\"#\" class=\"headline\" role=\"button\" id=\"faq_toggler__1\" aria-controls=\"faq_content__1\" aria-expanded=\"true\" class=\"headline active\">\r\n              <p class=\"h3 headline\">\r\n                Tem alguma quest\u00e3o sobre o produto?              <\/p>\r\n            <\/a>\r\n            <div class=\"filter-accordion_content accordion_content\" style=\"display: none;\">\r\n              \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f153076-o1\" lang=\"pt-PT\" dir=\"ltr\" data-wpcf7-id=\"153076\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt-pt\/wp-json\/wp\/v2\/products\/160279#wpcf7-f153076-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"153076\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"pt_PT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f153076-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"col lg_6\">\n\t<p><label for=\"firstname\">Nome pr\u00f3prio*<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"firstname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"firstname\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"col lg_6\">\n\t<p><label for=\"name\">Nome*<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"name\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"col lg_6\">\n\t<p><label for=\"company\">Empresa<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"company\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"col lg_6\">\n\t<p><label for=\"email\">Endere\u00e7o de correio eletr\u00f3nico*<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"col lg_12\">\n\t<p><label for=\"message\">A sua pergunta<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"message\"><\/textarea><\/span>\n\t<\/p>\n<\/div>\n<div class=\"col lg_12 checkbox\">\n\t<div>\n\t\t<p>Ap\u00f3s o envio do formul\u00e1rio, os meus dados ser\u00e3o utilizados para processar e responder ao meu pedido. Tomei conhecimento das <a href=\"https:\/\/wassermann-automation.com\/datenschutz\/\" target=\"_blank\">informa\u00e7\u00f5es sobre a prote\u00e7\u00e3o de dados<\/a>.\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"col lg_12 checkbox\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"kontakt\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"kontakt[]\" value=\"Sim\" \/><span class=\"wpcf7-list-item-label\">Sim<\/span><\/span><\/span><\/span>\n\t<\/p>\n\t<div>\n\t\t<p><label for=\"kontakt\">Autorizo a WASSERMANN TECHNOLOGIE GmbH a tratar regularmente os meus dados para o envio de uma newsletter por e-mail (informa\u00e7\u00f5es sobre ofertas, promo\u00e7\u00f5es, produtos e servi\u00e7os da WASSERMANN TECHNOLOGIE GmbH). Este consentimento \u00e9 volunt\u00e1rio e pode ser revogado a qualquer momento, sem necessidade de justifica\u00e7\u00e3o. Pode enviar o seu pedido de revoga\u00e7\u00e3o para <a href=\"mailto:info@wassermann-technologie.de\">info@wassermann-technologie.de<\/a>. Pode encontrar mais informa\u00e7\u00f5es sobre a prote\u00e7\u00e3o de dados <a href=\"https:\/\/wassermann-automation.com\/datenschutz\/\" target=\"_blank\">aqui<\/a>.<\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"col lg_12\">\n\t<p><span id=\"wpcf7-6a97b91b859c0-wrapper\" class=\"wpcf7-form-control-wrap cf7apps-honeypot-wrap honeypot-491-wrap\" data-cf7apps-honeypot=\"honeypot-491\" style=\"position:absolute;width:1px;height:1px;padding:0;margin:-1px;overflow:hidden;clip:rect(0,0,0,0);white-space:nowrap;border:0;\"><input type=\"hidden\" name=\"honeypot-491-random-hash\" value=\"20260902\"><input type=\"hidden\" name=\"honeypot-491-time-token\" value=\"MTc4ODMyODIxOQ==.054ceefeca2760c92232d62af0fd5b909e306b5f6aadd091a8274e45934801a6\"><label\n\t\t    for=\"wpcf7-6a97b91b859c0-field\"\n\t\t    class=\"hp-message\"\n        >Please leave this field empty.<\/label><input\n\t    id=\"wpcf7-6a97b91b859c0-field\"\n\t    \n\t    class=\"wpcf7-form-control wpcf7-text\"\n\t    type=\"text\"\n\t    name=\"9nsuhwtadhtr\"\n\t    value=\"\"\n\t    autocomplete=\"off\"\n\t    tabindex=\"1000\"\n\t    data-cf7apps-tabindex=\"1000\"\n    \/><\/span><input class=\"wpcf7-form-control wpcf7-submit has-spinner button outline blue\" type=\"submit\" value=\"Enviar\" \/>\n\t<\/p>\n<\/div>\n<p class=\"col lg_12\"><small>Os campos assinalados com * s\u00e3o obrigat\u00f3rios.<\/small>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n            <\/div>\r\n          <\/div>\r\n\r\n          <!-- Individuelle Produktkonfiguration starten? -->\r\n          <div class=\"filter-accordion_entry accordion_entry\" id=\"configuration-accordion\">\r\n            <a href=\"#\" class=\"headline\" role=\"button\" id=\"faq_toggler__1\" aria-controls=\"faq_content__1\" aria-expanded=\"true\" class=\"headline active\">\r\n              <p class=\"h3 headline\">\r\n                Iniciar a configura\u00e7\u00e3o personalizada do produto?              <\/p>\r\n            <\/a>\r\n            <div class=\"filter-accordion_content accordion_content\" style=\"display: none;\">\r\n              \r\n<form class=\"product_request \">\r\n\r\n    <input type=\"hidden\" name=\"baseurl\" value=\"https:\/\/wassermann-automation.com\/wp-content\/themes\/wassermann\">\r\n  <input type=\"hidden\" name=\"product\" value=\"FERRAMENTA-D N.\u00ba XXX\">\r\n  <input type=\"hidden\" name=\"permalink\" value=\"https:\/\/wassermann-group.com\/pt-pt\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\/werkzeugspeicher-tool-d\/\">\r\n  <input type=\"hidden\" name=\"lang\" value=\"pt-pt\">\r\n  <!-- <fieldset> -->\r\n    <span class=\"cp-honeypot-wrap\" style=\"display:none !important; visibility:hidden !important;\">\r\n      <input id=\"hp-6a97b91b87c54\" class=\"text-input\" type=\"text\" name=\"hp-42\" value=\"\"\r\n        size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\">\r\n    <\/span>\r\n  <!-- <\/fieldset> -->\r\n\r\n\r\n      \r\n<div class=\"filter-options filter-options-container\">      <div class=\"multi-selector \">\r\n\r\n\r\n        \r\n\r\n        <div class=\"select-field\">\r\n          <input type=\"text\" name=\"filter_1002\"\r\n            placeholder=\"storage architecture\" id=\"\" class=\"input-selector\" disabled>\r\n          <span class=\"down-arrow\"><i class=\"arrow down\"><\/i><\/span>\r\n        <\/div>\r\n        <!-- List of checkboxes and options -->\r\n        <div class=\"list\">\r\n          <div class=\"list-items\">\r\n                          <label for=\"1003\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"1003\"\r\n                  name=\"Compact circular storage system\" id=\"1003\">\r\n                Compact circular storage system              <\/label>\r\n                          <label for=\"1004\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"1004\"\r\n                  name=\"Expandable linear storage system\" id=\"1004\">\r\n                Expandable linear storage system              <\/label>\r\n            \r\n          <\/div>\r\n          <div class=\"resetfilter\">\r\n            <a href=\"\" class=\"reset\">\r\n              Repor sele\u00e7\u00e3o            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>        <div class=\"select-break\">&nbsp;<\/div>\r\n      <div class=\"slider-selector \" type=\"range\"\r\n        name=\"filter_852\" placeholder=\"Number of tools:\"\r\n        data-min=\"0\" data-max=\"999999\"\r\n        data-id=\"852\"\r\n        data-unit=\"pcs.\"\r\n        data-slider-stepwidth=\"1\">\r\n        <label>Number of tools:<\/label>\r\n        <div class=\"slider\"><\/div>\r\n        <div class=\"min-max-values\">\r\n          <span>0            pcs.<\/span>\r\n          <span>999999            pcs.<\/span>\r\n        <\/div>\r\n      <\/div>\r\n            <div class=\"multi-selector \">\r\n\r\n\r\n        \r\n\r\n        <div class=\"select-field\">\r\n          <input type=\"text\" name=\"filter_845\"\r\n            placeholder=\"Tool holder\" id=\"\" class=\"input-selector\" disabled>\r\n          <span class=\"down-arrow\"><i class=\"arrow down\"><\/i><\/span>\r\n        <\/div>\r\n        <!-- List of checkboxes and options -->\r\n        <div class=\"list\">\r\n          <div class=\"list-items\">\r\n                          <label for=\"883\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"883\"\r\n                  name=\"Capto C10\" id=\"883\">\r\n                Capto C10              <\/label>\r\n                          <label for=\"884\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"884\"\r\n                  name=\"SK 40\" id=\"884\">\r\n                SK 40              <\/label>\r\n                          <label for=\"885\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"885\"\r\n                  name=\"SK50\" id=\"885\">\r\n                SK50              <\/label>\r\n                          <label for=\"870\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"870\"\r\n                  name=\"HSK 25\" id=\"870\">\r\n                HSK 25              <\/label>\r\n                          <label for=\"886\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"886\"\r\n                  name=\"BT 40\" id=\"886\">\r\n                BT 40              <\/label>\r\n                          <label for=\"871\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"871\"\r\n                  name=\"HSK 32\" id=\"871\">\r\n                HSK 32              <\/label>\r\n                          <label for=\"887\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"887\"\r\n                  name=\"BT 50\" id=\"887\">\r\n                BT 50              <\/label>\r\n                          <label for=\"967\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"967\"\r\n                  name=\"All common\" id=\"967\">\r\n                All common              <\/label>\r\n                          <label for=\"872\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"872\"\r\n                  name=\"HSK 50\" id=\"872\">\r\n                HSK 50              <\/label>\r\n                          <label for=\"888\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"888\"\r\n                  name=\"ISO\" id=\"888\">\r\n                ISO              <\/label>\r\n                          <label for=\"873\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"873\"\r\n                  name=\"HSK 40\" id=\"873\">\r\n                HSK 40              <\/label>\r\n                          <label for=\"889\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"889\"\r\n                  name=\"KM 100\" id=\"889\">\r\n                KM 100              <\/label>\r\n                          <label for=\"874\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"874\"\r\n                  name=\"HSK 63\" id=\"874\">\r\n                HSK 63              <\/label>\r\n                          <label for=\"875\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"875\"\r\n                  name=\"HSK-A63\" id=\"875\">\r\n                HSK-A63              <\/label>\r\n                          <label for=\"876\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"876\"\r\n                  name=\"HSK 80\" id=\"876\">\r\n                HSK 80              <\/label>\r\n                          <label for=\"877\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"877\"\r\n                  name=\"HSK 100\" id=\"877\">\r\n                HSK 100              <\/label>\r\n                          <label for=\"1005\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"1005\"\r\n                  name=\"HSK 125\" id=\"1005\">\r\n                HSK 125              <\/label>\r\n                          <label for=\"878\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"878\"\r\n                  name=\"HSK-A100\" id=\"878\">\r\n                HSK-A100              <\/label>\r\n                          <label for=\"879\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"879\"\r\n                  name=\"Capto C4\" id=\"879\">\r\n                Capto C4              <\/label>\r\n                          <label for=\"880\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"880\"\r\n                  name=\"Capto C5\" id=\"880\">\r\n                Capto C5              <\/label>\r\n                          <label for=\"881\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"881\"\r\n                  name=\"Capto C6\" id=\"881\">\r\n                Capto C6              <\/label>\r\n                          <label for=\"882\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"882\"\r\n                  name=\"Capto C8\" id=\"882\">\r\n                Capto C8              <\/label>\r\n            \r\n          <\/div>\r\n          <div class=\"resetfilter\">\r\n            <a href=\"\" class=\"reset\">\r\n              Repor sele\u00e7\u00e3o            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>        <div class=\"select-break\">&nbsp;<\/div>\r\n      <div class=\"slider-selector \" type=\"range\"\r\n        name=\"filter_847\" placeholder=\"max. tool diameter\"\r\n        data-min=\"0\" data-max=\"999999\"\r\n        data-id=\"847\"\r\n        data-unit=\"mm\"\r\n        data-slider-stepwidth=\"10\">\r\n        <label>max. tool diameter<\/label>\r\n        <div class=\"slider\"><\/div>\r\n        <div class=\"min-max-values\">\r\n          <span>0            mm<\/span>\r\n          <span>999999            mm<\/span>\r\n        <\/div>\r\n      <\/div>\r\n            <div class=\"select-break\">&nbsp;<\/div>\r\n      <div class=\"slider-selector \" type=\"range\"\r\n        name=\"filter_846\" placeholder=\"max. tool length\"\r\n        data-min=\"0\" data-max=\"999999\"\r\n        data-id=\"846\"\r\n        data-unit=\"mm\"\r\n        data-slider-stepwidth=\"1\">\r\n        <label>max. tool length<\/label>\r\n        <div class=\"slider\"><\/div>\r\n        <div class=\"min-max-values\">\r\n          <span>0            mm<\/span>\r\n          <span>999999            mm<\/span>\r\n        <\/div>\r\n      <\/div>\r\n            <div class=\"select-break\">&nbsp;<\/div>\r\n      <div class=\"slider-selector \" type=\"range\"\r\n        name=\"filter_844\" placeholder=\"Tool weights\"\r\n        data-min=\"0\" data-max=\"999999\"\r\n        data-id=\"844\"\r\n        data-unit=\"kg\"\r\n        data-slider-stepwidth=\"1\">\r\n        <label>Tool weights<\/label>\r\n        <div class=\"slider\"><\/div>\r\n        <div class=\"min-max-values\">\r\n          <span>0            kg<\/span>\r\n          <span>999999            kg<\/span>\r\n        <\/div>\r\n      <\/div>\r\n            <div class=\"select-break\">&nbsp;<\/div>\r\n      <div class=\"slider-selector \" type=\"range\"\r\n        name=\"filter_987\" placeholder=\"Footprint\"\r\n        data-min=\"0\" data-max=\"999999\"\r\n        data-id=\"987\"\r\n        data-unit=\"m\u00b2\"\r\n        data-slider-stepwidth=\"0.1\">\r\n        <label>Footprint<\/label>\r\n        <div class=\"slider\"><\/div>\r\n        <div class=\"min-max-values\">\r\n          <span>0            m\u00b2<\/span>\r\n          <span>999999            m\u00b2<\/span>\r\n        <\/div>\r\n      <\/div>\r\n            <div class=\"select-break\">&nbsp;<\/div>\r\n      <div class=\"slider-selector \" type=\"range\"\r\n        name=\"filter_859\" placeholder=\"Dimensions - depth\"\r\n        data-min=\"0\" data-max=\"999999\"\r\n        data-id=\"859\"\r\n        data-unit=\"mm\"\r\n        data-slider-stepwidth=\"10\">\r\n        <label>Dimensions &#8211; depth<\/label>\r\n        <div class=\"slider\"><\/div>\r\n        <div class=\"min-max-values\">\r\n          <span>0            mm<\/span>\r\n          <span>999999            mm<\/span>\r\n        <\/div>\r\n      <\/div>\r\n            <div class=\"select-break\">&nbsp;<\/div>\r\n      <div class=\"slider-selector \" type=\"range\"\r\n        name=\"filter_860\" placeholder=\"Dimensions - width\"\r\n        data-min=\"0\" data-max=\"999999\"\r\n        data-id=\"860\"\r\n        data-unit=\"mm\"\r\n        data-slider-stepwidth=\"10\">\r\n        <label>Dimensions &#8211; width<\/label>\r\n        <div class=\"slider\"><\/div>\r\n        <div class=\"min-max-values\">\r\n          <span>0            mm<\/span>\r\n          <span>999999            mm<\/span>\r\n        <\/div>\r\n      <\/div>\r\n            <div class=\"select-break\">&nbsp;<\/div>\r\n      <div class=\"slider-selector \" type=\"range\"\r\n        name=\"filter_861\" placeholder=\"Dimensions - height\"\r\n        data-min=\"0\" data-max=\"999999\"\r\n        data-id=\"861\"\r\n        data-unit=\"mm\"\r\n        data-slider-stepwidth=\"10\">\r\n        <label>Dimensions &#8211; height<\/label>\r\n        <div class=\"slider\"><\/div>\r\n        <div class=\"min-max-values\">\r\n          <span>0            mm<\/span>\r\n          <span>999999            mm<\/span>\r\n        <\/div>\r\n      <\/div>\r\n            <div class=\"multi-selector \">\r\n\r\n\r\n        \r\n\r\n        <div class=\"select-field\">\r\n          <input type=\"text\" name=\"filter_992\"\r\n            placeholder=\"Terminal control\" id=\"\" class=\"input-selector\" disabled>\r\n          <span class=\"down-arrow\"><i class=\"arrow down\"><\/i><\/span>\r\n        <\/div>\r\n        <!-- List of checkboxes and options -->\r\n        <div class=\"list\">\r\n          <div class=\"list-items\">\r\n                          <label for=\"993\" class=\"task\">\r\n                <input type=\"checkbox\" value=\"993\"\r\n                  name=\"BECKHOFF TwinCAT3\" id=\"993\">\r\n                BECKHOFF TwinCAT3              <\/label>\r\n            \r\n          <\/div>\r\n          <div class=\"resetfilter\">\r\n            <a href=\"\" class=\"reset\">\r\n              Repor sele\u00e7\u00e3o            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>    <\/div>\r\n  \r\n<!-- \/\/CHECKBOXEN -->\r\n  <div class=\"options-container\">\r\n    <b>Op\u00e7\u00f5es:<\/b>\r\n          <div class=\"checkbox-options\">\r\n        <input type=\"checkbox\" name=\"MULTI-TOOL\" id=\"1011\" value=\"Ja\">\r\n        <label for=\"1011\">MULTI-TOOL<\/label>\r\n                  <span class=\"lg_2 info-wrapper\">\r\n            <div class=\"info-i\">i<\/div>\r\n            <div class=\"tooltip\" id=\"\">\r\n              For fast loading of up to 44 tools simultaneously, parallel with production.            <\/div>\r\n          <\/span>\r\n              <\/div>\r\n          <div class=\"checkbox-options\">\r\n        <input type=\"checkbox\" name=\"BALLUFF RFID\" id=\"1012\" value=\"Ja\">\r\n        <label for=\"1012\">BALLUFF RFID<\/label>\r\n                  <span class=\"lg_2 info-wrapper\">\r\n            <div class=\"info-i\">i<\/div>\r\n            <div class=\"tooltip\" id=\"\">\r\n              Automatic transmission of tool data via RFID            <\/div>\r\n          <\/span>\r\n              <\/div>\r\n      <\/div>\r\n\r\n\r\n  \r\n\r\n  <textarea id=\"message\" name=\"message\" rows=\"4\" cols=\"50\"\r\n    placeholder=\"N\u00e3o \u00e9 o mais adequado para si? Diga-nos quais s\u00e3o as suas necessidades. \"><\/textarea>\r\n\r\n\r\n  \r\n        <div class=\"basic_options_data filter-options\">\r\n  <p class=\"h3 headline\">\r\n    Transmitir dados b\u00e1sicos sobre a m\u00e1quina-ferramenta  <\/p>\r\n  <fieldset class=\"col lg_6\">\r\n    <span>Fabricante<\/span>\r\n    <span class=\"wpcf7-form-control-wrap\">\r\n      <input type=\"text\" name=\"manufacturer\" placeholder=\"\" value=\"\" size=\"40\"\r\n        class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\"\r\n        aria-required=\"true\" aria-invalid=\"false\">\r\n    <\/span>\r\n  <\/fieldset>\r\n  <fieldset class=\"col lg_6\">\r\n    <span>Tipo<\/span>\r\n    <span class=\"wpcf7-form-control-wrap\">\r\n      <input type=\"text\" name=\"type\" placeholder=\"\" value=\"\" size=\"40\"\r\n        class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\"\r\n        aria-required=\"true\" aria-invalid=\"false\">\r\n    <\/span>\r\n  <\/fieldset>\r\n\r\n  <fieldset class=\"col lg_6\">\r\n    <span>Controlo incl vers\u00e3o<\/span>\r\n    <span class=\"wpcf7-form-control-wrap\">\r\n      <input type=\"text\" name=\"control\" placeholder=\"\" value=\"\" size=\"40\"\r\n        class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\"\r\n        aria-required=\"true\" aria-invalid=\"false\">\r\n    <\/span>\r\n  <\/fieldset>\r\n\r\n  <div class=\"basic_options-container\">\r\n      <\/div>\r\n<\/div>      \r\n\r\n  <div class=\"contact_data\">\r\n    <p class=\"h3 headline\">Contactos<\/p>\r\n    <fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"153019\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"pt_PT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f153019-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset><fieldset class=\"col lg_6\">\n\t<p><span>Nome pr\u00f3prio*<\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"your-firstname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-firstname\" \/><\/span>\n\t<\/p>\n<\/fieldset><fieldset class=\"col lg_6\">\n\t<p><span>Nome*<\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t<\/p>\n<\/fieldset><fieldset class=\"col lg_6\">\n\t<p><span>Empresa<\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"company\" \/><\/span>\n\t<\/p>\n<\/fieldset><fieldset class=\"col lg_6\">\n\t<p><span>Endere\u00e7o de correio eletr\u00f3nico*<\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n<\/fieldset><fieldset class=\"col lg_12\">\n\t<p><span>Mensagem<\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"message_form\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"message_form\"><\/textarea><\/span>\n\t<\/p>\n<\/fieldset><fieldset class=\"col lg_12 checkbox\">\n\t<p>Ap\u00f3s o envio do formul\u00e1rio, os meus dados ser\u00e3o utilizados para processar e responder ao meu pedido. Tomei conhecimento das <a href=\"https:\/\/wassermann-automation.com\/datenschutz\/\" target=\"_blank\">informa\u00e7\u00f5es sobre a prote\u00e7\u00e3o de dados<\/a>.\n\t<\/p>\n<\/fieldset><fieldset class=\"col lg_12 checkbox\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"kontakt\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"kontakt[]\" value=\"Sim\" \/><span class=\"wpcf7-list-item-label\">Sim<\/span><\/span><\/span><\/span>\n\t<\/p>\n\t<p>Autorizo a WASSERMANN TECHNOLOGIE GmbH a tratar regularmente os meus dados para o envio de uma newsletter por e-mail (informa\u00e7\u00f5es sobre ofertas, promo\u00e7\u00f5es, produtos e servi\u00e7os da WASSERMANN TECHNOLOGIE GmbH). Este consentimento \u00e9 volunt\u00e1rio e pode ser revogado a qualquer momento, sem necessidade de justifica\u00e7\u00e3o. Pode enviar o seu pedido de revoga\u00e7\u00e3o para <a href=\"mailto:info@wassermann-technologie.de\">info@wassermann-technologie.de<\/a>. Pode encontrar mais informa\u00e7\u00f5es sobre a prote\u00e7\u00e3o de dados <a href=\"https:\/\/wassermann-automation.com\/datenschutz\/\" target=\"_blank\">aqui<\/a>.\n\t<\/p>\n<\/fieldset>  <\/div>\r\n\r\n  <fieldset>\r\n    <input type=\"submit\" class=\"button product_submit outline blue\"\r\n      value=\"Enviar\">\r\n  <\/fieldset>\r\n  <input type=\"hidden\" class=\"redirect\" value=\"https:\/\/wassermann-automation.com\/pt-pt\/vielen-dank-anfrage\/\">\r\n  <p class=\"col lg_12\" style=\"margin-top: 1rem\">\r\n    <small>Os campos assinalados com * s\u00e3o obrigat\u00f3rios.<\/small>\r\n  <\/p>\r\n  <div id=\"error_message_block\"><\/div>\r\n  <div id=\"success_message_block\" style=\"display:none\">\r\n    Obrigado pela sua mensagem! Entraremos em contacto consigo em breve.   <\/div>\r\n\r\n<\/form>            <\/div>\r\n          <\/div>\r\n\r\n        <\/div>\r\n        <!-- END Akkordion -->        \r\n<div class=\"button-controll-wrapper\" style=\"display: none;\">\r\n          <a href=\"#\" class=\"opendialog button blue outline\">\r\n            Solicitar configura\u00e7\u00e3o          <\/a>\r\n        <\/div>              <\/div>\n      <!-- END Filter -->\n    <\/div>\n    <!-- END Table -->\n  <\/div>\n  <!-- END config -->\n\n<\/div>\n  <!-- END col -->\n<\/div>\n<!-- END filter_Blick -->\n\r\n    <!-- SEO -->\n  \n  <div class=\"seo_textblock wassermann_block  grey_background\" data-source=\"160279\">\n    <!--<h2 class=\"custom_headline h1\" class=\"custom_headline h1\" id=\"terminais-de-ferramentas-automacao-cnc-da-wassermann-solucoes-personalizadas-para-a-sua-producao\">TERMINAIS DE FERRAMENTAS<\/h2>-->\n\n    <div>\n      \r\n\r\n<div id=\"block-657a17282f4f3\"  class=\"headline_icon wassermann_block\">\r\n  <div class=\"noborder\">\r\n        <h2 class=\"custom_headline h2\" class=\"custom_headline h2\" id=\"automacao-cnc-da-wassermann-solucoes-personalizadas-para-a-sua-producao\">\r\n              <span class=\"headline\">Automa\u00e7\u00e3o CNC da Wassermann<\/span>\r\n                    <strong class=\"subline\">Solu\u00e7\u00f5es personalizadas para a sua produ\u00e7\u00e3o<\/strong>\r\n          <\/h2>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"accordion-container accordion-block accordion-multi wassermann_block\">\r\n<!--\r\n    <div class=\"controlls\">\r\n        <a href=\"#\" class=\"button openall\">\r\n            <div class=\"closeall\" style=\"display:none\">\r\n                Fechar tudo            <\/div>\r\n\r\n            <div class=\"openall\">\r\n                Abrir tudo            <\/div>\r\n\r\n        <\/a>\r\n    <\/div> -->\r\n\r\n        <div class=\"accordion_entry\">\r\n        <a href=\"#\" role=\"button\" id=\"faq_toggler_block_b377f3c21b8319d9bd5e06f8c405eeae_1\" aria-controls=\"faq_content_block_b377f3c21b8319d9bd5e06f8c405eeae_1\" aria-expanded=\"false\" class=\"headline \">\r\n            <h3 class=\"custom_headline h3 font-light\"  class=\"custom_headline h3 font-light\"  id=\"porque-a-automatizacao-cnc-para-ferramentas\">Porqu\u00ea a automatiza\u00e7\u00e3o CNC para ferramentas?<\/h3>\r\n        <\/a>\r\n        <div id=\"faq_content_block_b377f3c21b8319d9bd5e06f8c405eeae_1\" class=\"accordion_content\" style=\"display:none\">\r\n            <div class=\"col stretch\">\r\n                <div\r\n                    class=\"col   lg_4 md_12  sm_12\">\r\n                                                            <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/09\/90-91-21-443_komp.jpg\" data-featherlight=\"image\">\r\n                        <div class=\"square-box box-shadow lazy\" id=\"child-240\"\r\n                            style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/09\/90-91-21-443_komp.jpg); background-size: cover\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/09\/90-91-21-443_komp-600x600.jpg\" class=\"print_only\" alt=\"\" srcset=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/09\/90-91-21-443_komp-600x600.jpg 600w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/09\/90-91-21-443_komp-150x150.jpg 150w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                            <div class=\"zoom-icon\">\r\n                                <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\"\r\n                                    alt=\"zoom\" width=\"40px\" height=\"40px\">\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                                                        <\/div>\r\n                \r\n                <div\r\n                    class=\"col   lg_8 md_12  sm_12\">\r\n                    <div class=\"content\">\r\n                        <div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"71cdad01-17ea-4428-8552-69d0ddce4d40\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p><strong>O armazenamento insuficiente de ferramentas reduz a produtividade<\/strong><\/p>\n<p>Um armaz\u00e9m de ferramentas demasiado pequeno pode limitar o rendimento e dificultar o caminho para a produ\u00e7\u00e3o n\u00e3o tripulada. Com um terminal TOOL, pode expandir o armaz\u00e9m da m\u00e1quina em 200 a 1000 ferramentas, ultrapassando as limita\u00e7\u00f5es t\u00e9cnicas e eliminando os obst\u00e1culos ao sucesso. <\/p>\n<p>Os nossos terminais TOOL optimizam a gest\u00e3o de ferramentas atrav\u00e9s do carregamento de ferramentas para encomendas futuras no armaz\u00e9m interno da m\u00e1quina enquanto a produ\u00e7\u00e3o ainda est\u00e1 em curso. Isto \u00e9 feito de forma eficiente de acordo com a frequ\u00eancia de utiliza\u00e7\u00e3o das ferramentas, o que significa que os espa\u00e7os livres do armaz\u00e9m s\u00e3o sempre preenchidos de forma sensata. <\/p>\n<p>A prop\u00f3sito: n\u00e3o tem de contactar o fabricante da m\u00e1quina para adaptar a gest\u00e3o de ferramentas ao sistema de controlo da m\u00e1quina &#8211; os nossos especialistas p\u00f5em em di\u00e1logo o software e o sistema de controlo.<\/p>\n<p><strong>Os sistemas de automa\u00e7\u00e3o CNC s\u00e3o a chave para transformar o processo de fabrico.<\/strong><\/p>\n<p>A Wassermann utiliza tecnologias inovadoras para elevar a um novo n\u00edvel os sistemas de automatiza\u00e7\u00e3o CNC normalizados. As nossas solu\u00e7\u00f5es minimizam o manuseamento manual de ferramentas, garantem a precis\u00e3o e proporcionam vantagens em termos de tempos de configura\u00e7\u00e3o e de funcionamento da m\u00e1quina. <\/p>\n<p>Veja as vantagens dos nossos sistemas de automa\u00e7\u00e3o CNC num relance:<\/p>\n<ul>\n<li><strong>Mais rendimento &#8211; <\/strong> Aumente a efici\u00eancia e o rendimento da produ\u00e7\u00e3o com a automatiza\u00e7\u00e3o CNC que optimiza o manuseamento de materiais.<\/li>\n<li><strong>Mais horas de fuso<\/strong> &#8211; Utiliza\u00e7\u00e3o \u00f3ptima da capacidade da m\u00e1quina e produ\u00e7\u00e3o n\u00e3o tripulada durante per\u00edodos mais longos.<\/li>\n<li><strong>Melhores margens &#8211;<\/strong> optimize a rentabilidade atrav\u00e9s de uma automatiza\u00e7\u00e3o CNC eficiente e reduza os custos.<\/li>\n<li><strong>Sem tamanhos de lote &#8211;<\/strong> Trabalhe de forma eficiente a partir do tamanho de lote 1 gra\u00e7as \u00e0s solu\u00e7\u00f5es flex\u00edveis de automa\u00e7\u00e3o CNC.<\/li>\n<li><strong>Reduzir a escassez de m\u00e3o de obra qualificada<\/strong> &#8211; Crie locais de trabalho modernos e modelos de turnos flex\u00edveis, libertando os trabalhadores de tarefas manuais.<\/li>\n<\/ul>\n<p>Experimente o futuro da automa\u00e7\u00e3o CNC com a Wassermann e aumente a efici\u00eancia e a competitividade da sua empresa.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mt-1 flex justify-start gap-3 empty:hidden\">\n<div class=\"text-gray-400 flex self-end lg:self-center justify-center lg:justify-start mt-0 gap-1 visible\"><\/div>\n<\/div>\n                                                <div class=\"button-controll-wrapper\">\r\n\r\n                            \r\n                            <div class=\"button-wrapper\">\r\n                                <a href=\"https:\/\/calendly.com\/wt-sauth\" class=\"button blue outline\" target=\"_blank\">\r\n                                                                        <span>Marque uma consulta  <\/span>\r\n                                                                                                        <\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <\/div>\r\n\r\n                <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n        <div class=\"accordion_entry\">\r\n        <a href=\"#\" role=\"button\" id=\"faq_toggler_block_b377f3c21b8319d9bd5e06f8c405eeae_2\" aria-controls=\"faq_content_block_b377f3c21b8319d9bd5e06f8c405eeae_2\" aria-expanded=\"false\" class=\"headline \">\r\n            <h3 class=\"custom_headline h3 font-light\" >Solu\u00e7\u00f5es sens\u00edveis de automa\u00e7\u00e3o CNC para ferramentas<\/h3>\r\n        <\/a>\r\n        <div id=\"faq_content_block_b377f3c21b8319d9bd5e06f8c405eeae_2\" class=\"accordion_content\" style=\"display:none\">\r\n            <div class=\"col stretch\">\r\n                <div\r\n                    class=\"col   lg_4 md_12  sm_12\">\r\n                                                            <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Greifer-eingefahren-4274.jpg\" data-featherlight=\"image\">\r\n                        <div class=\"square-box box-shadow lazy\" id=\"child-240\"\r\n                            style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Greifer-eingefahren-4274.jpg); background-size: cover\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Greifer-eingefahren-4274-600x600.jpg\" class=\"print_only\" alt=\"\" srcset=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Greifer-eingefahren-4274-600x600.jpg 600w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Greifer-eingefahren-4274-150x150.jpg 150w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                            <div class=\"zoom-icon\">\r\n                                <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\"\r\n                                    alt=\"zoom\" width=\"40px\" height=\"40px\">\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                                                        <\/div>\r\n                \r\n                <div\r\n                    class=\"col   lg_8 md_12  sm_12\">\r\n                    <div class=\"content\">\r\n                        <div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"5bf43d33-6ed6-40d5-80bd-986a1f01b85f\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p><strong>Exclusivamente connosco: a loja de ferramentas patenteada.<\/strong><\/p>\n<p>Para maximizar a densidade da embalagem, desenvolvemos um conceito de armazenamento patenteado para os nossos TERMINAIS DE FERRAMENTAS. Um sistema de tambor especial permite uma densidade de ferramentas que solu\u00e7\u00f5es compar\u00e1veis n\u00e3o conseguem alcan\u00e7ar no mesmo espa\u00e7o. <\/p>\n<p><strong>Da prova de conceito ao sucesso em apenas 12 semanas<\/strong><\/p>\n<p>Em 2013, nasceu a ideia de desenvolver uma nova solu\u00e7\u00e3o para o armazenamento e automatiza\u00e7\u00e3o de ferramentas. Ap\u00f3s apenas 12 semanas, a prova de conceito estava pronta em nossa unidade de produ\u00e7\u00e3o &#8211; desenvolvida, produzida, montada e comissionada pela WASSERMANN. O prot\u00f3tipo ainda hoje est\u00e1 ativo na nossa produ\u00e7\u00e3o e abastece uma das nossas m\u00e1quinas-ferramentas todos os dias.  <\/p>\n<p><strong>Distinguimo-nos com solu\u00e7\u00f5es de automatiza\u00e7\u00e3o CNC espec\u00edficas.<\/strong><\/p>\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"c02ec800-95f5-46ea-bad1-ecec384cef05\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>Com d\u00e9cadas de experi\u00eancia como maquinistas CNC, compreendemos exatamente o que impulsiona a sua produ\u00e7\u00e3o CNC e trabalhamos especificamente em fun\u00e7\u00e3o dos seus requisitos espec\u00edficos. Pode confiar em solu\u00e7\u00f5es personalizadas, duradouras e fi\u00e1veis. <\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>Com mais de 30 m\u00e1quinas-ferramentas em funcionamento, compreendemos n\u00e3o s\u00f3 as suas preocupa\u00e7\u00f5es t\u00e9cnicas, mas tamb\u00e9m os seus requisitos operacionais. Com a Wassermann, aumenta a efici\u00eancia, reduz os custos de investimento e encurta o per\u00edodo de amortiza\u00e7\u00e3o. Confie na Wassermann para aumentar a sua produtividade com sistemas de automa\u00e7\u00e3o CNC e otimizar a sua produ\u00e7\u00e3o.  <\/p>\n<p>A Wassermann \u00e9 sin\u00f3nimo de solu\u00e7\u00f5es \u00e0 medida &#8211; desde a moderniza\u00e7\u00e3o de m\u00e1quinas at\u00e9 \u00e0 otimiza\u00e7\u00e3o de processos existentes, oferecemos automa\u00e7\u00e3o CNC na perfei\u00e7\u00e3o.<\/p>\n<p><strong>Escolha um especialista em automa\u00e7\u00e3o CNC que n\u00e3o s\u00f3 desenvolva, mas tamb\u00e9m fabrique diariamente.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n                                                <div class=\"button-controll-wrapper\">\r\n\r\n                            \r\n                            <div class=\"button-wrapper\">\r\n                                <a href=\"https:\/\/wassermann-group.com\/pt-pt\/ueber-wassermann\/fertigung\/\" class=\"button blue outline\" target=\"_blank\">\r\n                                                                        <span>Produ\u00e7\u00e3o CNC na Wassermann<\/span>\r\n                                                                                                        <\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <\/div>\r\n\r\n                <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n        <div class=\"accordion_entry\">\r\n        <a href=\"#\" role=\"button\" id=\"faq_toggler_block_b377f3c21b8319d9bd5e06f8c405eeae_3\" aria-controls=\"faq_content_block_b377f3c21b8319d9bd5e06f8c405eeae_3\" aria-expanded=\"false\" class=\"headline \">\r\n            <h3 class=\"custom_headline h3 font-light\" >Manuseamento econ\u00f3mico de ferramentas com automa\u00e7\u00e3o CNC<\/h3>\r\n        <\/a>\r\n        <div id=\"faq_content_block_b377f3c21b8319d9bd5e06f8c405eeae_3\" class=\"accordion_content\" style=\"display:none\">\r\n            <div class=\"col stretch\">\r\n                <div\r\n                    class=\"col   lg_4 md_12  sm_12\">\r\n                                                            <a class=\"box\" href=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409.jpg\" data-featherlight=\"image\">\r\n                        <div class=\"square-box box-shadow lazy\" id=\"child-240\"\r\n                            style=\"background-image: url(https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409.jpg); background-size: cover\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"421\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409.jpg\" class=\"print_only\" alt=\"\" srcset=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409.jpg 2362w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409-250x176.jpg 250w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409-700x492.jpg 700w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409-768x539.jpg 768w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409-1536x1079.jpg 1536w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409-2048x1438.jpg 2048w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409-142x100.jpg 142w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409-120x84.jpg 120w, https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/08\/Wz-beladungsklappe-409-1920x1349.jpg 1920w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                            <div class=\"zoom-icon\">\r\n                                <img decoding=\"async\" src=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/zoom-image.svg\"\r\n                                    alt=\"zoom\" width=\"40px\" height=\"40px\">\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                                                        <\/div>\r\n                \r\n                <div\r\n                    class=\"col   lg_8 md_12  sm_12\">\r\n                    <div class=\"content\">\r\n                        <div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"ef018243-454d-4bdf-a2d3-1908b25a7a2f\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p><strong>FERRAMENTAS-TERMINAIS para a sua produ\u00e7\u00e3o CNC flex\u00edvel<\/strong><\/p>\n<p>Os nossos TERMINAIS DE FERRAMENTAS oferecem uma elevada densidade de embalagem de ferramentas e adaptam-se facilmente a qualquer pavilh\u00e3o de produ\u00e7\u00e3o. A grelha de altura integrada oferece a m\u00e1xima flexibilidade, mesmo com alturas de pavilh\u00e3o invulgares. Os locais de armazenamento s\u00e3o adaptados \u00e0 variedade de tipos de ferramentas e os nossos conceitos de transfer\u00eancia est\u00e3o preparados para diferentes designs de armaz\u00e9ns de ferramentas.  <\/p>\n<p>Pensamos n\u00e3o apenas em termos de solu\u00e7\u00f5es t\u00e9cnicas, mas tamb\u00e9m em termos de conceitos bem pensados. O n\u00famero e o tipo de m\u00e1quinas-ferramentas ligadas a um TOOL-TERMINAL podem mudar ao longo do tempo sem surpresas nas interfaces. J\u00e1 lig\u00e1mos com sucesso muitos terminais a m\u00e1quinas existentes e novas.  <\/p>\n<p>Os nossos TERMINAIS DE FERRAMENTAS harmonizam-se perfeitamente com a sua produ\u00e7\u00e3o CNC.<\/p>\n<p><strong>Aumento da produtividade sem novas aquisi\u00e7\u00f5es gra\u00e7as \u00e0 automatiza\u00e7\u00e3o CNC<br \/>\n<\/strong><\/p>\n<p>A compra de uma nova m\u00e1quina-ferramenta com um armaz\u00e9m de ferramentas maior n\u00e3o \u00e9 a \u00fanica op\u00e7\u00e3o para aumentar a produtividade. Na Wassermann, encorajamo-lo a verificar se a sua m\u00e1quina existente pode ser reequipada com sistemas de automa\u00e7\u00e3o CNC normalizados para ferramentas. Esta \u00e9 frequentemente a forma mais econ\u00f3mica de obter mais desempenho da sua m\u00e1quina existente.  <\/p>\n<p>Na pr\u00e1tica de maquina\u00e7\u00e3o complexa, oferecemos solu\u00e7\u00f5es para diferentes fabricantes de m\u00e1quinas e condi\u00e7\u00f5es de espa\u00e7o limitadas.<\/p>\n<p><strong>Porqu\u00ea automatizar as m\u00e1quinas existentes?<\/strong><\/p>\n<p>As m\u00e1quinas existentes oferecem frequentemente uma qualidade de produ\u00e7\u00e3o de primeira classe e est\u00e3o tecnicamente actualizadas. A automatiza\u00e7\u00e3o CNC direcionada de ferramentas e\/ou pe\u00e7as de trabalho utilizando sistemas de automatiza\u00e7\u00e3o CNC permite-lhe aumentar a produtividade sem comprometer a qualidade da produ\u00e7\u00e3o. <\/p>\n<p><strong>Solu\u00e7\u00f5es personalizadas para a sua produ\u00e7\u00e3o<\/strong><\/p>\n<p>A Wassermann oferece-lhe solu\u00e7\u00f5es personalizadas que s\u00e3o adaptadas com precis\u00e3o \u00e0 sua instala\u00e7\u00e3o. Isto permite-lhe obter o maior benef\u00edcio em termos de efici\u00eancia, investimento e amortiza\u00e7\u00e3o. As nossas solu\u00e7\u00f5es elevam a sua produ\u00e7\u00e3o ao pr\u00f3ximo n\u00edvel e concentramo-nos em satisfazer as suas necessidades.  <\/p>\n<p><strong>Com a Wassermann e a nossa automa\u00e7\u00e3o CNC, n\u00e3o s\u00f3 ganha produtividade, como tamb\u00e9m molda o futuro da sua produ\u00e7\u00e3o.<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mt-1 flex justify-start gap-3 empty:hidden\">\n<div class=\"text-gray-400 flex self-end lg:self-center justify-center lg:justify-start mt-0 gap-1 visible\"><\/div>\n<\/div>\n                                                <div class=\"button-controll-wrapper\">\r\n\r\n                            \r\n                            <div class=\"button-wrapper\">\r\n                                <a href=\"https:\/\/calendly.com\/wt-sauth\" class=\"button blue outline\" target=\"_blank\">\r\n                                                                        <span>Marque uma consulta<\/span>\r\n                                                                                                        <\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <\/div>\r\n\r\n                <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n    \r\n<\/div>\r\n    <\/div>\n  <\/div>\n\n<!-- SEO ENDE -->\r\n","protected":false},"excerpt":{"rendered":"<p>N\u00famero de ferramentas: 600<br \/>\nDi\u00e2metro da ferramenta: m\u00e1x. 280mm<br \/>\nComprimento da ferramenta: m\u00e1x. 500mm<br \/>\nPeso da ferramenta: m\u00e1x. 25kg  <\/p>\n","protected":false},"featured_media":156387,"menu_order":0,"template":"","products_option":[],"products_category":[1241,1242,1243,1244],"product_asset":[1240],"products_filter":[],"class_list":["post-160279","products","type-products","status-publish","has-post-thumbnail","hentry","products_category-automacao-para-maquinistas","products_category-terminais-de-ferramentas","products_category-maquinas-ferramenta-automacao-para-oem","products_category-terminais-de-ferramentas-oem","product_asset-sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CNC Automation: Armazenamento de ferramentas D<\/title>\n<meta name=\"description\" content=\"Automatiza\u00e7\u00e3o de m\u00e1quinas CNC, ferramentas e pe\u00e7as de trabalho - Armazenamento de ferramentas D \u25ba Consulta em linha\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wassermann-automation.com\/pt-pt\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\/werkzeugspeicher-tool-d\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CNC Automation: Armazenamento de ferramentas D\" \/>\n<meta property=\"og:description\" content=\"Automatiza\u00e7\u00e3o de m\u00e1quinas CNC, ferramentas e pe\u00e7as de trabalho - Armazenamento de ferramentas D \u25ba Consulta em linha\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wassermann-group.com\/pt-pt\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\/werkzeugspeicher-tool-d\/\" \/>\n<meta property=\"og:site_name\" content=\"Wassermann Technologie GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-28T11:18:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/og_image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\\\/werkzeugspeicher-tool-d\\\/\",\"url\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\\\/werkzeugspeicher-tool-d\\\/\",\"name\":\"CNC Automation: Armazenamento de ferramentas D\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/NEW\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\\\/werkzeugspeicher-tool-d\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\\\/werkzeugspeicher-tool-d\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wassermann-automation.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Tool-D.png\",\"datePublished\":\"2023-01-20T10:43:14+00:00\",\"dateModified\":\"2026-05-28T11:18:40+00:00\",\"description\":\"Automatiza\u00e7\u00e3o de m\u00e1quinas CNC, ferramentas e pe\u00e7as de trabalho - Armazenamento de ferramentas D \u25ba Consulta em linha\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\\\/werkzeugspeicher-tool-d\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\\\/werkzeugspeicher-tool-d\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\\\/werkzeugspeicher-tool-d\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wassermann-automation.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Tool-D.png\",\"contentUrl\":\"https:\\\/\\\/wassermann-automation.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Tool-D.png\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\\\/werkzeugspeicher-tool-d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FERRAMENTA-D N.\u00ba XXX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/NEW\\\/#website\",\"url\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/NEW\\\/\",\"name\":\"Wassermann Technologie GmbH\",\"description\":\"We think automatically\",\"publisher\":{\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/NEW\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/NEW\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/NEW\\\/#organization\",\"name\":\"Wassermann Technologie GmbH\",\"url\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/NEW\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/NEW\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wassermann-automation.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cropped-WASSERMANN-GROUP.png\",\"contentUrl\":\"https:\\\/\\\/wassermann-automation.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cropped-WASSERMANN-GROUP.png\",\"width\":314,\"height\":276,\"caption\":\"Wassermann Technologie GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/wassermann-group.com\\\/pt-pt\\\/NEW\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CNC Automation: Armazenamento de ferramentas D","description":"Automatiza\u00e7\u00e3o de m\u00e1quinas CNC, ferramentas e pe\u00e7as de trabalho - Armazenamento de ferramentas D \u25ba Consulta em linha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wassermann-automation.com\/pt-pt\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\/werkzeugspeicher-tool-d\/","og_locale":"pt_PT","og_type":"article","og_title":"CNC Automation: Armazenamento de ferramentas D","og_description":"Automatiza\u00e7\u00e3o de m\u00e1quinas CNC, ferramentas e pe\u00e7as de trabalho - Armazenamento de ferramentas D \u25ba Consulta em linha","og_url":"https:\/\/wassermann-group.com\/pt-pt\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\/werkzeugspeicher-tool-d\/","og_site_name":"Wassermann Technologie GmbH","article_modified_time":"2026-05-28T11:18:40+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2022\/03\/og_image.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wassermann-group.com\/pt-pt\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\/werkzeugspeicher-tool-d\/","url":"https:\/\/wassermann-group.com\/pt-pt\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\/werkzeugspeicher-tool-d\/","name":"CNC Automation: Armazenamento de ferramentas D","isPartOf":{"@id":"https:\/\/wassermann-group.com\/pt-pt\/NEW\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wassermann-group.com\/pt-pt\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\/werkzeugspeicher-tool-d\/#primaryimage"},"image":{"@id":"https:\/\/wassermann-group.com\/pt-pt\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\/werkzeugspeicher-tool-d\/#primaryimage"},"thumbnailUrl":"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2025\/08\/Tool-D.png","datePublished":"2023-01-20T10:43:14+00:00","dateModified":"2026-05-28T11:18:40+00:00","description":"Automatiza\u00e7\u00e3o de m\u00e1quinas CNC, ferramentas e pe\u00e7as de trabalho - Armazenamento de ferramentas D \u25ba Consulta em linha","breadcrumb":{"@id":"https:\/\/wassermann-group.com\/pt-pt\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\/werkzeugspeicher-tool-d\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wassermann-group.com\/pt-pt\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\/werkzeugspeicher-tool-d\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/wassermann-group.com\/pt-pt\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\/werkzeugspeicher-tool-d\/#primaryimage","url":"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2025\/08\/Tool-D.png","contentUrl":"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2025\/08\/Tool-D.png","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/wassermann-group.com\/pt-pt\/sistemas-de-armazenamento-e-carregamento-de-ferramentas-sistemas-de-armazenamento-e-carregamento-de-ferramentas-terminais-de-ferramentas\/werkzeugspeicher-tool-d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wassermann-group.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"FERRAMENTA-D N.\u00ba XXX"}]},{"@type":"WebSite","@id":"https:\/\/wassermann-group.com\/pt-pt\/NEW\/#website","url":"https:\/\/wassermann-group.com\/pt-pt\/NEW\/","name":"Wassermann Technologie GmbH","description":"We think automatically","publisher":{"@id":"https:\/\/wassermann-group.com\/pt-pt\/NEW\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wassermann-group.com\/pt-pt\/NEW\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/wassermann-group.com\/pt-pt\/NEW\/#organization","name":"Wassermann Technologie GmbH","url":"https:\/\/wassermann-group.com\/pt-pt\/NEW\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/wassermann-group.com\/pt-pt\/NEW\/#\/schema\/logo\/image\/","url":"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2025\/12\/cropped-WASSERMANN-GROUP.png","contentUrl":"https:\/\/wassermann-automation.com\/wp-content\/uploads\/2025\/12\/cropped-WASSERMANN-GROUP.png","width":314,"height":276,"caption":"Wassermann Technologie GmbH"},"image":{"@id":"https:\/\/wassermann-group.com\/pt-pt\/NEW\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/wassermann-automation.com\/pt-pt\/wp-json\/wp\/v2\/products\/160279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wassermann-automation.com\/pt-pt\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/wassermann-automation.com\/pt-pt\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":0,"href":"https:\/\/wassermann-automation.com\/pt-pt\/wp-json\/wp\/v2\/products\/160279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wassermann-automation.com\/pt-pt\/wp-json\/wp\/v2\/media\/156387"}],"wp:attachment":[{"href":"https:\/\/wassermann-automation.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=160279"}],"wp:term":[{"taxonomy":"products_option","embeddable":true,"href":"https:\/\/wassermann-automation.com\/pt-pt\/wp-json\/wp\/v2\/products_option?post=160279"},{"taxonomy":"products_category","embeddable":true,"href":"https:\/\/wassermann-automation.com\/pt-pt\/wp-json\/wp\/v2\/products_category?post=160279"},{"taxonomy":"product_asset","embeddable":true,"href":"https:\/\/wassermann-automation.com\/pt-pt\/wp-json\/wp\/v2\/product_asset?post=160279"},{"taxonomy":"products_filter","embeddable":true,"href":"https:\/\/wassermann-automation.com\/pt-pt\/wp-json\/wp\/v2\/products_filter?post=160279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}